{"id":3978,"date":"2025-02-03T14:24:54","date_gmt":"2025-02-03T13:24:54","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/menorca\/?p=3978"},"modified":"2025-07-18T09:57:27","modified_gmt":"2025-07-18T08:57:27","slug":"welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/algarve\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land\/","title":{"rendered":"Welche Zollfreigrenzen gelten bei der Einreise aus einem Nicht-EU-Land?","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Neben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren:<\/p>\n<p><strong>Tabakwaren<br \/>\n<\/strong>Wenn Sie mindestens 17 Jahre alt sind:<br \/>\n200 Zigaretten oder<br \/>\n100 Zigarillos oder<br \/>\n50 Zigarren oder<br \/>\n250 g Rauchtabak oder eine anteilige Zusammenstellung der Rauchwaren.<\/p>\n<p><strong>Alkohol und alkoholhaltige Getr\u00e4nke<br \/>\n<\/strong>Wenn Sie mindestens 17 Jahre alt sind:<br \/>\n1 l Spirituosen mit einem Alkoholgehalt von mehr als 22 % Vol. oder<br \/>\n1 l unverg\u00e4llter Ethylalkohol mit einem Alkoholgehalt von 80 % Vol. oder mehr oder<br \/>\n2 l Alkohol und alkoholische Getr\u00e4nke mit einem Alkoholgehalt von h\u00f6chstens 22 % Vol.<br \/>\noder eine anteilige Zusammenstellung dieser Waren und<br \/>\n4 l nicht sch\u00e4umende Weine<br \/>\n16 l Bier.<\/p>\n<p><strong>Arzneimittel<br \/>\n<\/strong>Die dem pers\u00f6nlichen Bedarf des Reisenden entsprechende Menge.<\/p>\n<p><strong>Andere Waren\/Souvenirs<br \/>\n<\/strong>Bis zu einem Warenwert von insgesamt 430 \u20ac sind diese einfuhrabgabenfrei. F\u00fcr Reisende unter 15 Jahren wird die Freimenge unabh\u00e4ngig vom gew\u00e4hlten Verkehrstr\u00e4ger auf 175 \u20ac festgesetzt; ausgenommen davon sind Goldlegierungen und -plattierungen in unbearbeitetem oder halbfertigem Zustand.<\/p>\n<p><strong>F\u00fcr \u00d6sterreich gelten folgende Vorschriften:<\/strong><\/p>\n<p>Freier Warenverkehr in der EU, aber mit Ausnahme von Tabakwaren aus EU-Staaten:<\/p>\n<p>Es ist verboten, Tabakerzeugnisse, die im Ausland erworben werden und auf denen die Warnhinweise nicht den Bestimmungen dieses Gesetzes (Warnhinweise in deutscher Sprache) entsprechen, \u00fcber die folgenden genannten Mengen nach \u00d6sterreich zu verbringen:<\/p>\n<p>200 Zigaretten oder<br \/>\n100 Zigarillos (h\u00f6chstens 3 g St\u00fcckgewicht) oder<br \/>\n50 Zigarren oder<br \/>\n250 g Rauchtabak oder<br \/>\neine anteilige Zusammenstellung dieser Waren bis h\u00f6chstens 250 g.<\/p>\n<p>\u00c4nderungen vorbehalten. Angaben ohne Gew\u00e4hr.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Neben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren: Tabakwaren Wenn Sie mindestens 17 Jahre alt sind: 200 Zigaretten oder 100 Zigarillos oder 50 Zigarren [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[192],"tags":[],"class_list":["post-3978","post","type-post","status-publish","format-standard","hentry","category-an-und-abreise-faq","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/posts\/3978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/comments?post=3978"}],"version-history":[{"count":3,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/posts\/3978\/revisions"}],"predecessor-version":[{"id":10974,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/posts\/3978\/revisions\/10974"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/media?parent=3978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/categories?post=3978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/algarve\/wp-json\/wp\/v2\/tags?post=3978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}