{"id":743,"date":"2024-12-02T21:40:24","date_gmt":"2024-12-02T20:40:24","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/menorca\/uncategorized\/handgepaeck\/"},"modified":"2025-10-07T16:35:49","modified_gmt":"2025-10-07T14:35:49","slug":"welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/faq\/an-und-abreise-faq\/welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug\/","title":{"rendered":"Welche Regelungen gelten f\u00fcr das Handgep\u00e4ck im Flugzeug?","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>F\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt.<\/p>\n<p><strong>Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck:<\/strong><\/p>\n<ul class=\"square\">\n<li>Reisende d\u00fcrfen Fl\u00fcssigkeiten nur in Beh\u00e4ltern mitnehmen, deren Fassungsverm\u00f6gen maximal 100 ml betr\u00e4gt.<\/li>\n<li>Alle Fl\u00fcssigkeitsbeh\u00e4lter m\u00fcssen in einem Plastikbeutel (maximales Fassungsverm\u00f6gen: 1 l) an den Sicherheitskontrollstellen vorgezeigt werden. Dieser muss transparent und verschlie\u00dfbar sein. Es besteht f\u00fcr die Flugh\u00e4fen keine Pflicht, Plastikbeutel f\u00fcr die Reisenden bereitzuhalten! Fl\u00fcssigkeiten sind beispielsweise Getr\u00e4nke, Gels, Lotions, Cremes, Zahnpasta und Rasierschaum.<\/li>\n<\/ul>\n<p><strong>In folgenden F\u00e4llen gelten Ausnahmen:<\/strong><\/p>\n<ul class=\"square\">\n<li>Babynahrung, -milch oder -s\u00e4fte f\u00fcr mitreisende Babys und Kleinkinder d\u00fcrfen mitgef\u00fchrt werden.<\/li>\n<li>Pers\u00f6nlich verschriebene und w\u00e4hrend des Fluges ben\u00f6tigte Medikamente, wie zum Beispiel Insulin, d\u00fcrfen mitgef\u00fchrt werden. Es erfordert eine \u00e4rztliche Bescheinigung, die best\u00e4tigt, dass der\/die Reisende diese Medikamente ben\u00f6tigt.<\/li>\n<\/ul>\n<p>Im Flughafen hinter den Sicherheitskontrollen erworbene Fl\u00fcssigkeiten d\u00fcrfen im Handgep\u00e4ck mitgef\u00fchrt werden.<\/p>\n<p><strong>Bitte beachten Sie:<\/strong> Bei Zwischenlandungen oder Wechsel des Flugzeugs (Drehkreuzfl\u00fcge) m\u00fcssen Sie in der Regel erneut durch die Handgep\u00e4ckkontrolle, d. h. Sie m\u00fcssen die aufgef\u00fchrten Regeln erneut beachten. Das bedeutet, dass Sie nun auch im Duty-free-Shop erworbene Fl\u00fcssigkeiten (Parf\u00fcm, Getr\u00e4nkeflaschen etc.) nur in einer durchsichtigen Plastikt\u00fcte und nur bis jeweils 100 ml mit sich f\u00fchren d\u00fcrfen, da sonst der Zoll die erworbenen Fl\u00fcssigkeiten einbeh\u00e4lt.<\/p>\n<p>Zus\u00e4tzlich sind Reisende dazu verpflichtet, bei der Sicherheitskontrolle ihre M\u00e4ntel, Jacken, Blazer oder Sakkos auszuziehen und gro\u00dfe elektronische Ger\u00e4te, wie zum Beispiel Notebooks, aus den Taschen herauszunehmen.<\/p>\n<p>Allt\u00e4gliche Objekte wie Korkenzieher, Scheren oder andere scharfe Gegenst\u00e4nde, die als Waffen verwendet werden k\u00f6nnten, d\u00fcrfen nicht im Handgep\u00e4ck bef\u00f6rdert werden. Gleiches gilt f\u00fcr entz\u00fcndliche oder explosionsgef\u00e4hrdete Gegenst\u00e4nde oder Substanzen, wie z. B. Feuerwerksk\u00f6rper oder Spraydosen mit Gefahrstoffkennzeichnung.<\/p>\n<p>\u00c4nderungen und Abweichungen (je nach Fluggesellschaft) vorbehalten.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>F\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt. Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck: [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[192],"tags":[],"class_list":["post-743","post","type-post","status-publish","format-standard","hentry","category-an-und-abreise-faq","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/posts\/743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/comments?post=743"}],"version-history":[{"count":6,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/posts\/743\/revisions"}],"predecessor-version":[{"id":9977,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/posts\/743\/revisions\/9977"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/media?parent=743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/categories?post=743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/bulgarien-sonnenstrand\/wp-json\/wp\/v2\/tags?post=743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}