{"id":9413,"date":"2025-03-23T13:31:13","date_gmt":"2025-03-23T12:31:13","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/djerba\/uncategorized\/tipps-von-a-bis-z\/"},"modified":"2025-10-24T14:49:07","modified_gmt":"2025-10-24T13:49:07","slug":"tipps-von-a-bis-z","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/djerba\/infos-a-z\/rund-um-ihr-zielgebiet\/tipps-von-a-bis-z\/","title":{"rendered":"Tipps von A bis Z","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<h3>Ihr Urlaubsratgeber<\/h3>\n<p>Denken Sie bitte daran: Sie sind als Gast in ein arabisches Land gereist. Respektieren Sie die Menschen mit Ihren Eigenarten, Sitten und Gebr\u00e4uchen. Wenn Sie etwas nicht verstehen, scheuen Sie sich nicht nachzufragen!<\/p>\n<p><strong>An-\/Abreisetag:<\/strong><br \/>\nNach internationaler Regelung erfolgt der Check-in ab 14 Uhr. Am Abreisetag m\u00fcssen die Zimmer bis 12 Uhr verlassen werden. Bitte haben Sie Verst\u00e4ndnis, dass Sie bei einer Anreise am Vormittag nicht direkt Ihr Zimmer beziehen k\u00f6nnen, da dieses erst noch f\u00fcr Sie gereinigt wird. Die Zimmerverteilung obliegt der jeweiligen Hotelf\u00fchrung. Die Verpflegung bei Halbpension beginnt am Anreisetag mit dem Abendessen und endet am Abreisetag mit dem Fr\u00fchst\u00fcck. Bei Anreise am sp\u00e4ten Abend oder in der Nacht sind die Hotels nicht verpflichtet, Ihnen noch ein Essen bereitzustellen.<\/p>\n<p><strong>Apotheke:<\/strong><br \/>\nSie hei\u00dft hier \u201ePharmacie\u201c oder \u201ePharmacie de nuit\u201c (Nachtapotheke) und ist mit einem gr\u00fcnen Malteserkreuz gekennzeichnet. In vielen Apotheken werden auch Drogerieartikel gef\u00fchrt. Lassen Sie sich f\u00fcr Medikamente immer eine Quittung ausstellen. Um mitgebrachte Medikamente nachkaufen zu k\u00f6nnen, bringen Sie am besten die Originalverpackung mit, damit der\/die Apotheker\/-in Ihnen ein gleichwertiges Pr\u00e4parat anbieten kann.<\/p>\n<p><strong>Arzt:<\/strong><br \/>\nBei Bedarf k\u00f6nnen Sie einen Arzt \u00fcber die Hotelrezeption rufen lassen. Die Behandlung muss immer vor Ort in bar und in der Landesw\u00e4hrung bezahlt werden. Die Bezahlung erfolgt gegen Quittung, die Sie bei Ihrer Krankenkasse oder Reisekrankenversicherung einreichen k\u00f6nnen. Bei einem Klinik- oder Krankenhausaufenthalt kontaktieren Sie bitte umgehend Ihre Versicherung und Ihre zust\u00e4ndige Reiseleitung.<\/p>\n<p><strong>Ausfl\u00fcge:<\/strong><br \/>\nDjerba und Zarzis liegen geografisch so g\u00fcnstig, dass Sie als Urlauber davon profitieren. Das Meer l\u00e4dt zu geselligen Bootsausfl\u00fcgen ein, das Festland ist schnell zu erreichen und die W\u00fcste in S\u00fcdtunesien ist sehr nah. Bus- und Landroverausfl\u00fcge bieten Ihnen Abenteuer. Sie entdecken Sitten und Gebr\u00e4uche und erleben orientalisches Flair. Kompetente Beratung und Buchung nur bei Ihrer Reiseleitung.<\/p>\n<p><strong>Botschaft:<\/strong><br \/>\nBei Verlust Ihres Reisepasses oder Personalausweises kontaktieren Sie bitte umgehend die Deutsche Botschaft in Tunis bzw. die Botschaft Ihrer jeweiligen Nationalit\u00e4t. Je nach Verlust ist ein Besuch der Botschaft zur Ausstellung eines Ersatzausweises erforderlich.<\/p>\n<p><strong>Einkaufen:<\/strong><br \/>\nHier ist Handeln die Regel Nummer 1! Zahlen Sie auf M\u00e4rkten und in den Bazaren maximal 30% des Ihnen vorgeschlagenen Preises, orientieren Sie sich zuvor in Warenh\u00e4usern oder Gesch\u00e4ften mit Festpreisen. In jeder gr\u00f6\u00dferen Stadt gibt es zus\u00e4tzlich Markttage (Orte und Tage erfahren Sie bei Ihrer Reiseleitung). Typische Souvenirs sind Teppiche, Lederwaren, Keramik sowie Gold- oder Silberwaren.<\/p>\n<p><strong>Fotografieren:<\/strong><br \/>\nDer Koran verbietet das Abbilden von Personen. Im Zweifelsfall sollte durch eine kleine Geste die Erlaubnis zum Fotografieren eingeholt werden. Milit\u00e4rische Anlagen, Polizei und betende Gl\u00e4ubige d\u00fcrfen nicht fotografiert werden! In den meisten Museen ist das Fotografieren gegen eine kleine Geb\u00fchr erlaubt.<\/p>\n<p><strong>Geld:<\/strong><br \/>\nDie tunesische W\u00e4hrung ist der Dinar (TND). Ein Dinar sind 1.000 Millimes. Die gr\u00f6\u00dfte Banknote ist der 50-Dinar-Schein. Man sollte immer Kleingeld zur Verf\u00fcgung haben, da gro\u00dfe Scheine h\u00e4ufig nicht gewechselt werden k\u00f6nnen. Bargeld k\u00f6nnen Sie an der Hotelrezeption oder bei der Bank zum jeweiligen Tageskurs wechseln. Der R\u00fccktausch ist nur bei der Bank am Flughafen gegen Vorlage der Wechselquittung m\u00f6glich. Bitte achten Sie beim Geldwechsel darauf, dass auf der Wechselquittung ein Stempel des Hotels oder der Wechselstube zu finden ist. Ansonsten verweigern die Banken am Flughafen evtl. den R\u00fccktausch. <strong>Die Ein- und Ausfuhr der tunesischen W\u00e4hrung ist verboten.<\/strong><\/p>\n<p><strong>Kleidung:<\/strong><br \/>\nVerzichten Sie auf das Tragen von wertvollem, sichtbarem Schmuck. Es sollte au\u00dferhalb von Strand und Hotelzone keine offenherzige Kleidung getragen werden. Minir\u00f6cke und kurze Hosen sind vor allem nicht gern gesehen. Wenn Sie eine heilige St\u00e4tte (z.B. eine Moschee) besuchen, dann achten Sie auf dezente Kleidung, die Schultern und Knie bedeckt. Am Strand ist das Sonnen \u201eoben ohne\u201c gesetzlich verboten und kann sogar polizeilich geahndet werden.<\/p>\n<p><strong>Mietwagen:<\/strong><br \/>\nSie m\u00f6chten flexibel Ihr Urlaubsziel erkunden? Ihre Reiseleitung vermittelt Ihnen gerne ein Auto unseres Mietwagenpartners \u2013 auf Wunsch auch mit Chauffeur. Die H\u00f6chstgeschwindigkeit innerorts betr\u00e4gt 50 km\/h, auf Landstra\u00dfen 90 km\/h und auf Autobahnen 110 km\/h. Es besteht Anschnallpflicht. Fahren Sie vorausschauend, denn gerade abends sind viele Motorroller oder andere Fahrzeuge nur schlecht beleuchtet und schwer zu sehen.<\/p>\n<p><strong>Post:<\/strong><br \/>\nIn jedem Ort gibt es diverse Post\u00e4mter. Die \u00d6ffnungszeiten erfragen Sie bitte bei Ihrer Reiseleitung. Wenn Sie eine Karte verschicken m\u00f6chten, dann achten Sie auf den Vermerk \u201epar avion\u201c oder \u201eper Luftpost\u201c. Zielland nicht vergessen, damit die Karte auch tats\u00e4chlich ankommt. Die H\u00f6he des Portos erfahren Sie an der Rezeption oder von Ihrer Reiseleitung.<\/p>\n<p><strong>Safe:<\/strong><br \/>\nAlle Wertgegenst\u00e4nde sollten Sie im Safe aufbewahren. Tickets, Reisep\u00e4sse, Ausweise etc. ben\u00f6tigen Sie nicht am Strand und auch nicht bei Ausfl\u00fcgen. Weder Ihr Hotelier, noch Ihr Veranstalter, haftet f\u00fcr Wertsachen, die nicht im Safe aufbewahrt wurden. F\u00fchren Sie immer nur kleine Geldbetr\u00e4ge und eine Kopie Ihres Ausweises mit sich.<\/p>\n<p><strong>Taxi:<\/strong><br \/>\nDas Taxi ist ein sehr beliebtes und preiswertes Verkehrsmittel. Alle Taxis sind mit einem Taxameter ausgestattet \u2013 achten Sie bei Fahrtbeginn auf dessen Inbetriebnahme! F\u00fcr Fahrten ab 21 Uhr wird ein Nachtzuschlag von 50% erhoben. Sie finden Taxis meistens direkt vor Ihrem Hotel. An der Stra\u00dfe k\u00f6nnen Sie mit einem kleinen Handzeichen ein Taxi anhalten. Die gelben Taxis d\u00fcrfen die Insel Djerba nicht verlassen! \u00dcberregionale Taxis\/Sammeltaxis sind die Louages. Es handelt sich hierbei um wei\u00dfe Kombis, die mit einem roten, blauen oder gelben Streifen gekennzeichnet sind. Diese Taxis haben keinen Taxameter. Bitte handeln Sie den Preis vor Fahrtbeginn aus.<\/p>\n<p><strong>Telefon:<\/strong><br \/>\nTelefonate k\u00f6nnen \u00fcber die Rezeption vermittelt werden. Da dies sehr teuer ist, empfiehlt es sich, eine \u00f6ffentliche Telefonzelle zu nutzen.<\/p>\n<p><strong>Trinkgeld:<\/strong><br \/>\nEin kleines Trinkgeld wird in allen Servicebereichen erwartet. Richtwert: 10% vom Rechnungsbetrag. F\u00fcr ein Zimmerm\u00e4dchen oder einen Koffertr\u00e4ger ist 1 TND pro Tag\/Service angemessen.<\/p>\n<p><strong>Trinkwasser:<\/strong><br \/>\nDas Leitungswasser ist als Trinkwasser nicht zu empfehlen, zum Z\u00e4hneputzen jedoch geeignet. Mineralwasser erhalten Sie in Ihrem Hotel.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Ihr Urlaubsratgeber Denken Sie bitte daran: Sie sind als Gast in ein arabisches Land gereist. Respektieren Sie die Menschen mit Ihren Eigenarten, Sitten und Gebr\u00e4uchen. Wenn Sie etwas nicht verstehen, scheuen Sie sich nicht nachzufragen! An-\/Abreisetag: Nach internationaler Regelung erfolgt der Check-in ab 14 Uhr. Am Abreisetag m\u00fcssen die Zimmer bis 12 Uhr verlassen werden. [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":2,"featured_media":9414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[45],"tags":[],"class_list":["post-9413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rund-um-ihr-zielgebiet","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/comments?post=9413"}],"version-history":[{"count":3,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9413\/revisions"}],"predecessor-version":[{"id":12335,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9413\/revisions\/12335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/media\/9414"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/media?parent=9413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/categories?post=9413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/tags?post=9413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}