{"id":9445,"date":"2025-03-23T13:32:03","date_gmt":"2025-03-23T12:32:03","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/djerba\/uncategorized\/erriadh\/"},"modified":"2025-04-30T07:13:03","modified_gmt":"2025-04-30T06:13:03","slug":"erriadh","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/djerba\/infos-a-z\/orte-infos-a-z\/erriadh\/","title":{"rendered":"Erriadh","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Hier befindet sich eine der bekanntesten Synagogen der Welt: La Ghriba. Sie ist offen f\u00fcr Besucher (au\u00dfer an j\u00fcdischen Feiertagen) und beherbergt die \u00e4lteste Tora der Welt. Besuchen Sie au\u00dferdem das au\u00dfergew\u00f6hnliche Open-Air-Museum Djerbahood und bewundern Sie die Arbeiten hunderter K\u00fcnstler aus 30 Nationen, die ihrer Kreativit\u00e4t an W\u00e4nden und Fassaden der H\u00e4user freien Lauf gelassen haben.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Hier befindet sich eine der bekanntesten Synagogen der Welt: La Ghriba. Sie ist offen f\u00fcr Besucher (au\u00dfer an j\u00fcdischen Feiertagen) und beherbergt die \u00e4lteste Tora der Welt. Besuchen Sie au\u00dferdem das au\u00dfergew\u00f6hnliche Open-Air-Museum Djerbahood und bewundern Sie die Arbeiten hunderter K\u00fcnstler aus 30 Nationen, die ihrer Kreativit\u00e4t an W\u00e4nden und Fassaden der H\u00e4user freien Lauf [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":2,"featured_media":9446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":null,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[46],"tags":[],"class_list":["post-9445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orte-infos-a-z","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/comments?post=9445"}],"version-history":[{"count":1,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9445\/revisions"}],"predecessor-version":[{"id":9447,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/posts\/9445\/revisions\/9447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/media\/9446"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/media?parent=9445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/categories?post=9445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/djerba\/wp-json\/wp\/v2\/tags?post=9445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}