{"id":1938,"date":"2024-12-12T17:58:44","date_gmt":"2024-12-12T16:58:44","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/ibiza\/?page_id=1938"},"modified":"2026-04-10T10:55:21","modified_gmt":"2026-04-10T08:55:21","slug":"an-und-abreise","status":"publish","type":"page","link":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/an-und-abreise\/","title":{"rendered":"An- und Abreise"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1938\" class=\"elementor elementor-1938\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-219230c e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"219230c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f0f4540 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"f0f4540\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-335963c e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"335963c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d72b51 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4d72b51\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane-arrival\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 448H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h608c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM44.81 205.66l88.74 80a62.607 62.607 0 0 0 25.47 13.93l287.6 78.35c26.48 7.21 54.56 8.72 81 1.36 29.67-8.27 43.44-21.21 47.25-35.71 3.83-14.5-1.73-32.71-23.37-54.96-19.28-19.82-44.35-32.79-70.83-40l-97.51-26.56L282.8 30.22c-1.51-5.81-5.95-10.35-11.66-11.91L206.05.58c-10.56-2.88-20.9 5.32-20.71 16.44l47.92 164.21-102.2-27.84-27.59-67.88c-1.93-4.89-6.01-8.57-11.02-9.93L52.72 64.75c-10.34-2.82-20.53 5-20.72 15.88l.23 101.78c.19 8.91 6.03 17.34 12.58 23.25z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd4442 elementor-widget elementor-widget-heading\" data-id=\"6cd4442\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1afdb8 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e1afdb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"red-square\"><li>Informationen zur Ankunft am Flughafen in Ihrer Urlaubsregion<\/li><li>Wo finde ich die Reiseleitung und den Transfer?<\/li><li>Kontaktinformationen<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d467dc elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"6d467dc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ibiza\/anreise\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur Anreise-Information<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f61fbaf e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"f61fbaf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1df6af elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e1df6af\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane-departure\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 448H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h608c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM80.55 341.27c6.28 6.84 15.1 10.72 24.33 10.71l130.54-.18a65.62 65.62 0 0 0 29.64-7.12l290.96-147.65c26.74-13.57 50.71-32.94 67.02-58.31 18.31-28.48 20.3-49.09 13.07-63.65-7.21-14.57-24.74-25.27-58.25-27.45-29.85-1.94-59.54 5.92-86.28 19.48l-98.51 49.99-218.7-82.06a17.799 17.799 0 0 0-18-1.11L90.62 67.29c-10.67 5.41-13.25 19.65-5.17 28.53l156.22 98.1-103.21 52.38-72.35-36.47a17.804 17.804 0 0 0-16.07.02L9.91 230.22c-10.44 5.3-13.19 19.12-5.57 28.08l76.21 82.97z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e7bba3 elementor-widget elementor-widget-heading\" data-id=\"0e7bba3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecae940 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ecae940\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"red-square\"><li>Transferinformationen und Abholzeitenabfrage<\/li><li>Kontaktinformationen und Telefonnummern<\/li><li>Transferabmeldung<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f106c62 elementor-align-left elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"f106c62\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ibiza\/abreise-und-transfers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur Abreise-Information<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-09dd9c2 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"09dd9c2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce26146 elementor-widget elementor-widget-global elementor-global-1242 elementor-widget-text-editor\" data-id=\"ce26146\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"background-color: #878787; color: #ffffff; padding: 5px 10px;\">Wichtige Links<\/h3><div style=\"padding: 0px 10px;\"><div><div style=\"margin-bottom: -15px; font-weight: bold;\">Rail&amp;Fly<\/div><ul class=\"red-square\"><li><a href=\"https:\/\/rldev.dts.dmcit.tech\/wp-content\/uploads\/rail_fly_buchungshilfe_einloesung_0724.pdf\" target=\"_blank\" rel=\"noopener\">Information zur Einl\u00f6sung des Rail &amp; Fly Tickets (PDF)<\/a><\/li><li><a href=\"https:\/\/rldev.dts.dmcit.tech\/wp-content\/uploads\/rail_fly_buchungshilfe_umbuchung_0724.pdf\">Information zur Umbuchung eines eingel\u00f6sten Rail &amp; Fly Tickets (PDF)<\/a><\/li><\/ul><\/div><div style=\"margin-bottom: -15px; font-weight: bold;\">Deutschland<\/div><ul class=\"red-square\"><li><a href=\"https:\/\/www.auswaertiges-amt.de\/de\/ReiseUndSicherheit\/reise-und-sicherheitshinweise\" target=\"_blank\" rel=\"noopener\">Ausw\u00e4rtiges Amt: Reise- und Sicherheitshinweise<\/a><\/li><\/ul><div style=\"margin-bottom: -15px; font-weight: bold;\">\u00d6sterreich<\/div><ul class=\"red-square\"><li><a href=\"https:\/\/www.bmeia.gv.at\/reise-aufenthalt\/reiseinformation\/\" target=\"_blank\" rel=\"noopener\">Bundesministerium Europ\u00e4ische und internationale Angelegenheiten: Reiseinformationen<\/a><\/li><\/ul><div style=\"margin-bottom: -15px; font-weight: bold;\">Schweiz<\/div><ul class=\"red-square\"><li><a href=\"https:\/\/www.eda.admin.ch\/eda\/de\/home.html\" target=\"_blank\" rel=\"noopener\">Eidgen\u00f6ssisches Departement f\u00fcr ausw\u00e4rtige Angelegenheiten EDA<\/a><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-1a6f3c8 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"1a6f3c8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccef65d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ccef65d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ An- und Abreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ac268 elementor-widget__width-initial acc-faq elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ae-post-blocks-adv\" data-id=\"97ac268\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_accordion_state&quot;:&quot;all_closed&quot;}\" data-widget_type=\"ae-post-blocks-adv.accordion\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"ae-outer-wrapper ae-height-100\" >\n\n\t\t\t\n\t\t\t<div class=\"ae-post-collection elementor-accordion ae-accordion\" role=\"tablist\" data-transition-speed=\"300\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-662345161\" t_id=\"662345161\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tab\" aria-controls=\"ae-tab-content-662345161\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Regelungen gelten f\u00fcr das Handgep\u00e4ck im Flugzeug?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-662345161\" t_id=\"662345161\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-662345161\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-97ac268\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tF\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt. Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck: Reisende d\u00fcrfen Fl\u00fcssigkeiten nur in Beh\u00e4ltern mitnehmen, deren Fassungsverm\u00f6gen maximal 100 ml betr\u00e4gt. Alle Fl\u00fcssigkeitsbeh\u00e4lter m\u00fcssen in einem Plastikbeutel (maximales Fassungsverm\u00f6gen: 1 l) an den Sicherheitskontrollstellen vorgezeigt werden. Dieser muss transparent und verschlie\u00dfbar sein. Es besteht f\u00fcr die Flugh\u00e4fen keine Pflicht, Plastikbeutel f\u00fcr die Reisenden...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-662345162\" t_id=\"662345162\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tab\" aria-controls=\"ae-tab-content-662345162\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise aus einem Nicht-EU-Land?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-662345162\" t_id=\"662345162\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-662345162\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-97ac268\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tNeben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren: Tabakwaren Wenn Sie mindestens 17 Jahre alt sind: 200 Zigaretten oder 100 Zigarillos oder 50 Zigarren oder 250 g Rauchtabak oder eine anteilige Zusammenstellung der Rauchwaren. Alkohol und alkoholhaltige Getr\u00e4nke Wenn Sie mindestens 17 Jahre alt sind: 1 l Spirituosen mit einem Alkoholgehalt von mehr als 22 % Vol. oder 1 l unverg\u00e4llter Ethylalkohol mit einem Alkoholgehalt von 80 % Vol....\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-662345163\" t_id=\"662345163\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tab\" aria-controls=\"ae-tab-content-662345163\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise in die Schweiz?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-662345163\" t_id=\"662345163\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-662345163\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-97ac268\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tEinfuhr von Waren durch Privatpersonen Generell gilt eine Freigrenze von 150 SFr bei Waren f\u00fcr den privaten Gebrauch, die pers\u00f6nlich im Reiseverkehr eingef\u00fchrt werden. Liegt der Gesamtwert der mitgef\u00fchrten Waren \u00fcber 150 SFr, so sind alle Waren abgabenpflichtig. Freimengen und -grenzen werden nur einmal pro Person und Tag gew\u00e4hrt. Es gelten folgende Freimengen: Alkoholische Getr\u00e4nke Personen ab 17 Jahren d\u00fcrfen einmal pro Tag abgabenfrei folgende Mengen einf\u00fchren: 5 l alkoholische Getr\u00e4nke bis 18 % Vol. und 1 l \u00fcber 18 % Vol. einf\u00fchren. Dar\u00fcber hinaus gelten folgende Zollabgaben: Alkoholische Getr\u00e4nke bis 18 % Vol.: 2 SFr\/l Alkoholische Getr\u00e4nke \u00fcber 18...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-in-die-schweiz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-662345164\" t_id=\"662345164\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tab\" aria-controls=\"ae-tab-content-662345164\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei Reisen innerhalb der EU?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-662345164\" t_id=\"662345164\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-662345164\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-97ac268\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tGrunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen: Parfum: Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist. Arzneimittel: Nur f\u00fcr den pers\u00f6nlichen Bedarf. Kaffee: 10 kg Alkoholische Getr\u00e4nke: 10 l Spirituosen 10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops) 20 l Lik\u00f6rwein, Wermutwein 90 l Wein (davon h\u00f6chstens 60 l Schaumwein) 110 l Bier Bei der Einreise nach Deutschland: Tabakwaren: 800 Zigaretten oder 400 Zigarillos oder 200 Zigarren oder 1 kg Rauchtabak Bei der Einreise nach \u00d6sterreich: F\u00fcr die private Einfuhr von Tabakerzeugnissen nach \u00d6sterreich gilt: Tabakwaren, die im Ausland erworben...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div> <!-- end .ae-outer-wrapper -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592f6c0 elementor-widget elementor-widget-image\" data-id=\"592f6c0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"575\" height=\"460\" src=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-content\/uploads\/sites\/5\/shape_reiseleitung_1_mobil_grau-1.jpg\" class=\"attachment-large size-large wp-image-10108\" alt=\"\" srcset=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-content\/uploads\/sites\/5\/shape_reiseleitung_1_mobil_grau-1.jpg 575w, https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-content\/uploads\/sites\/5\/shape_reiseleitung_1_mobil_grau-1-300x240.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-793a92b e-con-full elementor-hidden-mobile e-flex ae-bg-gallery-type-default e-con e-parent\" data-id=\"793a92b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-e92efb4 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-child\" data-id=\"e92efb4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba3b345 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ba3b345\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ An- und Abreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b779cbc elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ae-post-blocks-adv\" data-id=\"b779cbc\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_accordion_state&quot;:&quot;all_closed&quot;}\" data-widget_type=\"ae-post-blocks-adv.accordion\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"ae-outer-wrapper ae-height-100\" >\n\n\t\t\t\n\t\t\t<div class=\"ae-post-collection elementor-accordion ae-accordion\" role=\"tablist\" data-transition-speed=\"300\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-34805091201\" t_id=\"34805091201\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tab\" aria-controls=\"ae-tab-content-34805091201\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Regelungen gelten f\u00fcr das Handgep\u00e4ck im Flugzeug?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-34805091201\" t_id=\"34805091201\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-34805091201\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-b779cbc\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tF\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt. Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck: Reisende d\u00fcrfen Fl\u00fcssigkeiten nur in Beh\u00e4ltern mitnehmen, deren Fassungsverm\u00f6gen maximal 100 ml betr\u00e4gt. Alle Fl\u00fcssigkeitsbeh\u00e4lter m\u00fcssen in einem Plastikbeutel (maximales Fassungsverm\u00f6gen: 1 l) an den Sicherheitskontrollstellen vorgezeigt werden. Dieser muss transparent und verschlie\u00dfbar sein. Es besteht f\u00fcr die Flugh\u00e4fen keine Pflicht, Plastikbeutel f\u00fcr die Reisenden...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-34805091202\" t_id=\"34805091202\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tab\" aria-controls=\"ae-tab-content-34805091202\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise aus einem Nicht-EU-Land?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-34805091202\" t_id=\"34805091202\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-34805091202\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-b779cbc\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tNeben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren: Tabakwaren Wenn Sie mindestens 17 Jahre alt sind: 200 Zigaretten oder 100 Zigarillos oder 50 Zigarren oder 250 g Rauchtabak oder eine anteilige Zusammenstellung der Rauchwaren. Alkohol und alkoholhaltige Getr\u00e4nke Wenn Sie mindestens 17 Jahre alt sind: 1 l Spirituosen mit einem Alkoholgehalt von mehr als 22 % Vol. oder 1 l unverg\u00e4llter Ethylalkohol mit einem Alkoholgehalt von 80 % Vol....\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-34805091203\" t_id=\"34805091203\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tab\" aria-controls=\"ae-tab-content-34805091203\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise in die Schweiz?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-34805091203\" t_id=\"34805091203\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-34805091203\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-b779cbc\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tEinfuhr von Waren durch Privatpersonen Generell gilt eine Freigrenze von 150 SFr bei Waren f\u00fcr den privaten Gebrauch, die pers\u00f6nlich im Reiseverkehr eingef\u00fchrt werden. Liegt der Gesamtwert der mitgef\u00fchrten Waren \u00fcber 150 SFr, so sind alle Waren abgabenpflichtig. Freimengen und -grenzen werden nur einmal pro Person und Tag gew\u00e4hrt. Es gelten folgende Freimengen: Alkoholische Getr\u00e4nke Personen ab 17 Jahren d\u00fcrfen einmal pro Tag abgabenfrei folgende Mengen einf\u00fchren: 5 l alkoholische Getr\u00e4nke bis 18 % Vol. und 1 l \u00fcber 18 % Vol. einf\u00fchren. Dar\u00fcber hinaus gelten folgende Zollabgaben: Alkoholische Getr\u00e4nke bis 18 % Vol.: 2 SFr\/l Alkoholische Getr\u00e4nke \u00fcber 18...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-in-die-schweiz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-34805091204\" t_id=\"34805091204\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tab\" aria-controls=\"ae-tab-content-34805091204\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei Reisen innerhalb der EU?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-34805091204\" t_id=\"34805091204\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-34805091204\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-b779cbc\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tGrunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen: Parfum: Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist. Arzneimittel: Nur f\u00fcr den pers\u00f6nlichen Bedarf. Kaffee: 10 kg Alkoholische Getr\u00e4nke: 10 l Spirituosen 10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops) 20 l Lik\u00f6rwein, Wermutwein 90 l Wein (davon h\u00f6chstens 60 l Schaumwein) 110 l Bier Bei der Einreise nach Deutschland: Tabakwaren: 800 Zigaretten oder 400 Zigarillos oder 200 Zigarren oder 1 kg Rauchtabak Bei der Einreise nach \u00d6sterreich: F\u00fcr die private Einfuhr von Tabakerzeugnissen nach \u00d6sterreich gilt: Tabakwaren, die im Ausland erworben...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/ibiza\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div> <!-- end .ae-outer-wrapper -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anreise Informationen zur Ankunft am Flughafen in Ihrer Urlaubsregion Wo finde ich die Reiseleitung und den Transfer? Kontaktinformationen Zur Anreise-Information Abreise Transferinformationen und Abholzeitenabfrage Kontaktinformationen und Telefonnummern Transferabmeldung Zur Abreise-Information Wichtige Links Rail&amp;Fly Information zur Einl\u00f6sung des Rail &amp; Fly Tickets (PDF) Information zur Umbuchung eines eingel\u00f6sten Rail &amp; Fly Tickets (PDF) Deutschland Ausw\u00e4rtiges Amt: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":6393,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"seitenkategorien":[],"class_list":["post-1938","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":20,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/1938\/revisions"}],"predecessor-version":[{"id":14332,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/1938\/revisions\/14332"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/media?parent=1938"}],"wp:term":[{"taxonomy":"seitenkategorien","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/seitenkategorien?post=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}