{"id":2790,"date":"2025-01-14T17:31:50","date_gmt":"2025-01-14T16:31:50","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/ibiza\/?page_id=2790"},"modified":"2025-05-09T12:26:05","modified_gmt":"2025-05-09T10:26:05","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2790\" class=\"elementor elementor-2790\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-6501422 e-con-full e-flex ae-bg-gallery-type-default e-con e-parent\" data-id=\"6501422\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f7f3304 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-child\" data-id=\"f7f3304\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b41d65 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"3b41d65\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/rldev.dts.dmcit.tech\/wp-content\/uploads\/pmi-rl-2024-2.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-68af436 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"68af436\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf13fc elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"0cf13fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Sie brauchen Hilfe oder haben Fragen?<\/h2>\nViele Fragen versuchen wir bereits in unserem Bereich <a href=\"\/ibiza\/kategorie\/faq\/\">FAQ (h\u00e4ufig gestellte Fragen)<\/a> zu beantworten. Wenn Sie dort die gesuchte Information nicht finden, kontaktieren Sie gerne das \u00f6rtliche Team der Reiseleitung \u00fcber das nachfolgende Formular.\n<strong>Bitte beachten Sie, dass die Bearbeitung nur w\u00e4hrend der B\u00fcrozeiten erfolgt.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-34a0e0c e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"34a0e0c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3034547 elementor-widget elementor-widget-heading\" data-id=\"3034547\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bitte treffen Sie eine Auswahl:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb88cc4 elementor-widget elementor-widget-formidable\" data-id=\"bb88cc4\" data-element_type=\"widget\" data-widget_type=\"formidable.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"frm_forms  with_frm_style frm_style_der-style\" id=\"frm_form_1_container\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\"><form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_ajax_submit  frm_pro_form \" id=\"form_kontaktformular\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\"><div class=\"frm_form_fields \"><fieldset><legend class=\"frm_screen_reader\">Kontaktformular<\/legend><div class=\"frm_fields_container\"><input type=\"hidden\" name=\"frm_action\" value=\"create\" \/><input type=\"hidden\" name=\"form_id\" value=\"1\" \/><input type=\"hidden\" name=\"frm_hide_fields_1\" id=\"frm_hide_fields_1\" value=\"\" \/><input type=\"hidden\" name=\"form_key\" value=\"kontaktformular\" \/><input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/><input type=\"hidden\" id=\"frm_submit_entry_1\" name=\"frm_submit_entry_1\" value=\"3291852b4c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ibiza\/wp-json\/wp\/v2\/pages\/2790\" \/><div id=\"frm_field_11_container\" class=\"frm_form_field form-field  frm_top_container\"><label for=\"field_3ymy7\" id=\"field_3ymy7_label\" class=\"frm_primary_label\">Haben Sie Ihre Urlaubsreise bereits angetreten?<span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><select name=\"item_meta[11]\" id=\"field_3ymy7\"  data-frmval=\"bitte w\u00e4hlen Sie eine Option:\" data-invmsg=\"Haben Sie Ihre Urlaubsreise bereits angetreten? ist ung\u00fcltig\" aria-invalid=\"false\"  ><option  value=\"bitte w\u00e4hlen Sie eine Option:\" selected='selected'>bitte w\u00e4hlen Sie eine Option:<\/option><option  value=\"Nein, ich habe vorab eine Frage.\">Nein, ich habe vorab eine Frage.<\/option><option  value=\"Ja, heute ist mein Anreisetag.\">Ja, heute ist mein Anreisetag.<\/option><option  value=\"Ja, ich bin bereits am Urlaubsort.\">Ja, ich bin bereits am Urlaubsort.<\/option><option  value=\"Ich bin bereits wieder zur\u00fcck.\">Ich bin bereits wieder zur\u00fcck.<\/option><\/select><\/div><div id=\"frm_field_14_container\" class=\"frm_form_field  frm_html_container form-field\">Bitte beachten Sie, dass sich unser Team ausschlie\u00dflich um Ihre Anliegen w\u00e4hrend der Reise k\u00fcmmert.<\/p><p><strong>F\u00fcr alle Fragen vor Reiseantritt :\u00a0 Wenden Sie sich bitte an Ihr Reiseb\u00fcro oder Online-Buchungsportal.<\/strong><\/div><div id=\"frm_field_28_container\" class=\"frm_form_field form-field  frm_top_container\"><label for=\"field_l65t5\" id=\"field_l65t5_label\" class=\"frm_primary_label\">Sind Sie bereits am Flughafen am Urlaubsort und haben eine Frage zum Transfer?<span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><select name=\"item_meta[28]\" id=\"field_l65t5\"  data-frmval=\"bitte w\u00e4hlen Sie eine Option\" data-invmsg=\"Sind Sie bereits am Flughafen am Urlaubsort und haben eine Frage zum Transfer? ist ung\u00fcltig\" aria-invalid=\"false\"  ><option  value=\"bitte w\u00e4hlen Sie eine Option\" selected='selected'>bitte w\u00e4hlen Sie eine Option<\/option><option  value=\"ja\">ja<\/option><option  value=\"nein\">nein<\/option><\/select><\/div><div id=\"frm_field_18_container\" class=\"frm_form_field  frm12 frm_first frm_html_container form-field\"><p>Bitte informieren Sie sich zuerst <a href=\"\/ibiza\/anreise\/\">auf unserer Anreiseseite<\/a>. Hier finden Sie viele Informationen zur Ankunft in Ihrem Urlaubsgebiet und gebuchten Transfers.<\/p><\/div><div id=\"frm_field_29_container\" class=\"frm_form_field form-field  frm_top_container\"><label for=\"field_engf5\" id=\"field_engf5_label\" class=\"frm_primary_label\">Haben Sie eine Frage zur R\u00fcckreise (Abholzeit, Transfer)?<span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><select name=\"item_meta[29]\" id=\"field_engf5\"  data-frmval=\"bitte w\u00e4hlen Sie eine Option\" data-invmsg=\"Haben Sie eine Frage zur R\u00fcckreise (Abholzeit, Transfer)? ist ung\u00fcltig\" aria-invalid=\"false\"  ><option  value=\"bitte w\u00e4hlen Sie eine Option\" selected='selected'>bitte w\u00e4hlen Sie eine Option<\/option><option  value=\"ja\">ja<\/option><option  value=\"nein\">nein<\/option><\/select><\/div><div id=\"frm_field_24_container\" class=\"frm_form_field  frm_html_container form-field\"><p>Informieren Sie sich bitte zuerst <a href=\"\/ibiza\/abreise-und-transfers\/\">auf unserer R\u00fcckreiseseite<\/a>. Hier finden Sie auch die Abholzeitenabfrage.<\/p><\/div><div id=\"frm_field_26_container\" class=\"frm_form_field frm_section_heading form-field \"><h3 class=\"frm_pos_top frm_section_spacing\">Kontaktformular<\/h3><div id=\"frm_field_1_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\"><label for=\"field_qh4icy\" id=\"field_qh4icy_label\" class=\"frm_primary_label\">Ihr Name<span class=\"frm_required\" aria-hidden=\"true\">*<\/span><\/label><input  type=\"text\" id=\"field_qh4icy\" name=\"item_meta[1]\" value=\"\"  data-sectionid=\"26\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Ihr Name ist ung\u00fcltig\" aria-invalid=\"false\"   aria-describedby=\"frm_desc_field_qh4icy\" \/><div class=\"frm_description\" id=\"frm_desc_field_qh4icy\">Bitte geben Sie Vor- und Nachnamen an.<\/div><\/div><div id=\"frm_field_3_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\"><label for=\"field_29yf4d\" id=\"field_29yf4d_label\" class=\"frm_primary_label\">Ihre E-Mail-Adresse<span class=\"frm_required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"field_29yf4d\" name=\"item_meta[3]\" value=\"\"  data-sectionid=\"26\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Please enter a valid email address\" aria-invalid=\"false\"  \/><\/div><div id=\"frm_field_197_container\" class=\"frm_form_field form-field  frm_top_container frm_first frm_sixth frm_other_container\"><label for=\"field_kqwr4\" id=\"field_kqwr4_label\" class=\"frm_primary_label\">L\u00e4ndervorwahl<span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><select name=\"item_meta[197]\" id=\"field_kqwr4\"  data-sectionid=\"26\"  data-invmsg=\"L\u00e4ndervorwahl ist ung\u00fcltig\" aria-invalid=\"false\"  ><option  value=\"\" selected='selected'> <\/option><option  value=\"DE +49\">DE +49<\/option><option  value=\"AT +43\">AT +43<\/option><option  value=\"CH +41\">CH +41<\/option><option  value=\"andere (bitte eingeben)\" class=\"frm_other_trigger\">andere (bitte eingeben)<\/option><\/select><label for=\"field_kqwr4-otext\" class=\"frm_screen_reader frm_hidden\">L\u00e4ndervorwahl<\/label><input type=\"text\" id=\"field_kqwr4-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][197]\" value=\"\" \/><\/div><div id=\"frm_field_7_container\" class=\"frm_form_field form-field  frm_top_container frm10\"><label for=\"field_1vyn8\" id=\"field_1vyn8_label\" class=\"frm_primary_label\">Ihre Handynummer <small>(ohne Leerzeichen)<\/small><span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><input type=\"tel\" id=\"field_1vyn8\" name=\"item_meta[7]\" value=\"\"  data-sectionid=\"26\"  data-invmsg=\"Ihre Handynummer &lt;small&gt;(ohne Leerzeichen)&lt;\/small&gt; ist ung\u00fcltig\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/><\/div><div id=\"frm_field_4_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\"><label for=\"field_e6lis6\" id=\"field_e6lis6_label\" class=\"frm_primary_label\">Betreff<span class=\"frm_required\" aria-hidden=\"true\">*<\/span><\/label><input  type=\"text\" id=\"field_e6lis6\" name=\"item_meta[4]\" value=\"\"  data-sectionid=\"26\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Betreff ist ung\u00fcltig\" aria-invalid=\"false\"   \/><\/div><div id=\"frm_field_25_container\" class=\"frm_form_field form-field  frm_top_container\"><label for=\"field_67gja\" id=\"field_67gja_label\" class=\"frm_primary_label\">Ihre Vorgangsnummer (optional)<span class=\"frm_required\" aria-hidden=\"true\"><\/span><\/label><input  type=\"text\" id=\"field_67gja\" name=\"item_meta[25]\" value=\"\"  data-sectionid=\"26\"  data-invmsg=\"Ihre Vorgangsnummer (optional) ist ung\u00fcltig\" aria-invalid=\"false\"   aria-describedby=\"frm_desc_field_67gja\" \/><div class=\"frm_description\" id=\"frm_desc_field_67gja\">Diese Information hilft uns dabei, Ihre Anfrage schneller zu bearbeiten. Sie finden die Vorgangsnummer in Ihren Reiseunterlagen.<\/div><\/div><div id=\"frm_field_5_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\"><label for=\"field_9jv0r1\" id=\"field_9jv0r1_label\" class=\"frm_primary_label\">Ihre Nachricht<span class=\"frm_required\" aria-hidden=\"true\">*<\/span><\/label><textarea name=\"item_meta[5]\" id=\"field_9jv0r1\" rows=\"5\"  data-sectionid=\"26\"  placeholder=\"Bitte keine Kreditkartendaten \u00fcber dieses Formular senden!\" data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Ihre Nachricht ist ung\u00fcltig\" aria-invalid=\"false\"  ><\/textarea><\/div><div id=\"frm_field_8_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container vertical_radio\"><div  id=\"field_j4ug2_label\" class=\"frm_primary_label\">DSE<span class=\"frm_required\" aria-hidden=\"true\">*<\/span><\/div><div class=\"frm_opt_container\" aria-labelledby=\"field_j4ug2_label\" role=\"group\"><div class=\"frm_checkbox\" id=\"frm_checkbox_8-26-0\"><label  for=\"field_j4ug2-0\"><input type=\"checkbox\" name=\"item_meta[8][]\" id=\"field_j4ug2-0\" value=\"Ich habe die &lt;a href=&quot;https:\/\/dertour-reiseleitung.com\/datenschutzerklaerung\/&quot;&gt;Datenschutzerkl\u00e4rung&lt;\/a&gt; zur Kenntnis genommen.\"  data-sectionid=\"26\"  data-reqmsg=\"Pflichtfeld\" data-invmsg=\"DSE ist ung\u00fcltig\" aria-invalid=\"false\"   aria-required=\"true\"  \/> Ich habe die <a href=\"https:\/\/dertour-reiseleitung.com\/datenschutzerklaerung\/\">Datenschutzerkl\u00e4rung<\/a> zur Kenntnis genommen.<\/label><\/div><div class=\"frm_checkbox\" id=\"frm_checkbox_8-26-1\"><label  for=\"field_j4ug2-1\"><input type=\"checkbox\" name=\"item_meta[8][]\" id=\"field_j4ug2-1\" value=\"Ich willige ein, dass meine personenbezogenen Daten wie Kontaktdaten und Kommunikation f\u00fcr die Bearbeitung meiner Anfrage verarbeitet werden d\u00fcrfen, ferner ist mir bewusst, dass diese Verarbeitung auch meine besonderen personenbezogenen Daten im Sinne des Art. 9 DSGVO wie Gesundheit umfassen kann, sofern ich diese freiwillig mitgeteilt habe.\"  data-sectionid=\"26\"  data-reqmsg=\"Pflichtfeld\" data-invmsg=\"DSE ist ung\u00fcltig\" aria-invalid=\"false\"   \/> Ich willige ein, dass meine personenbezogenen Daten wie Kontaktdaten und Kommunikation f\u00fcr die Bearbeitung meiner Anfrage verarbeitet werden d\u00fcrfen, ferner ist mir bewusst, dass diese Verarbeitung auch meine besonderen personenbezogenen Daten im Sinne des Art. 9 DSGVO wie Gesundheit umfassen kann, sofern ich diese freiwillig mitgeteilt habe.<\/label><\/div><\/div><\/div><input type=\"hidden\" name=\"item_meta[9]\" id=\"field_h0det\" value=\"\"  data-sectionid=\"26\" \/><\/div><div id=\"frm_field_23_container\" class=\"frm_form_field  frm_html_container form-field\">Bitte beachten Sie, dass sich unser Team ausschlie\u00dflich um Ihre Anliegen w\u00e4hrend der Reise k\u00fcmmert.<\/p><p><strong>F\u00fcr alle Fragen nach der Reise:\u00a0 Wenden Sie sich bitte an die Kundenbetreuung (siehe Reiseunterlagen).\u00a0<\/strong><\/div><div id=\"frm_field_6_container\" class=\"frm_form_field form-field \"><div class=\"frm_submit frm_flex\"><button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Senden<\/button><\/div><\/div><input type=\"hidden\" name=\"item_key\" value=\"\" \/><div class=\"frm__673b936abcceb\"><label for=\"frm_email_1\" >&nbsp;<\/label><input  id=\"frm_email_1\" type=\"email\" class=\"frm_verify\" name=\"frm__673b936abcceb\" value=\"\"  \/><\/div><input name=\"frm_state\" type=\"hidden\" value=\"G6gkVxT8b4vSzdIkYxaGYRVls6EzgM9Z9xJozMJCIsQ=\" \/><\/div><\/fieldset><\/div><\/form><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-af1eb3e e-con-full e-flex ae-bg-gallery-type-default e-con e-parent\" data-id=\"af1eb3e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b138a6 elementor-widget__width-initial elementor-widget-mobile__width-inherit ae-grid-default overlay-h-pos-center overlay-v-pos-middle elementor-widget elementor-widget-ae-post-blocks-adv\" data-id=\"2b138a6\" data-element_type=\"widget\" data-settings=\"{&quot;grid_columns&quot;:1,&quot;grid_pagination_scroll_top_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_pagination_scroll_top_offset_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;grid_columns_tablet&quot;:&quot;2&quot;,&quot;grid_columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"ae-post-blocks-adv.grid\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"ae-post-overlay\">\n\t\t\t\t<div class=\"ae-post-overlay-wrapper\">\n\t\t\t\t\t<div class=\"ae-post-overlay-icon\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-sync\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M440.65 12.57l4 82.77A247.16 247.16 0 0 0 255.83 8C134.73 8 33.91 94.92 12.29 209.82A12 12 0 0 0 24.09 224h49.05a12 12 0 0 0 11.67-9.26 175.91 175.91 0 0 1 317-56.94l-101.46-4.86a12 12 0 0 0-12.57 12v47.41a12 12 0 0 0 12 12H500a12 12 0 0 0 12-12V12a12 12 0 0 0-12-12h-47.37a12 12 0 0 0-11.98 12.57zM255.83 432a175.61 175.61 0 0 1-146-77.8l101.8 4.87a12 12 0 0 0 12.57-12v-47.4a12 12 0 0 0-12-12H12a12 12 0 0 0-12 12V500a12 12 0 0 0 12 12h47.35a12 12 0 0 0 12-12.6l-4.15-82.57A247.17 247.17 0 0 0 255.83 504c121.11 0 221.93-86.92 243.55-201.82a12 12 0 0 0-11.8-14.18h-49.05a12 12 0 0 0-11.67 9.26A175.86 175.86 0 0 1 255.83 432z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ae-post-overlay-text\">\n\t\t\t\t\t\tLoading...\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ae-outer-wrapper ae-height-100\" data-source=\"manual_selection\" data-pid=\"2790\" data-wid=\"2b138a6\" data-disable_scroll_on_ajax_load=\"no\" data-pagination_scroll_top_offset=\"0\" >\n\t\t\t\n\t\t<div class=\"ae-post-collection\" >\n\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-2b138a6\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-1179\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1179\" class=\"elementor elementor-1179\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-f6aa7b8 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"f6aa7b8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b81170 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"3b81170\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virtuelle Betreuung im Urlaubsgebiet Ibiza &amp; Formentera<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1071845 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1071845\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mobile-alt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 0H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h224c26.5 0 48-21.5 48-48V48c0-26.5-21.5-48-48-48zM160 480c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm112-108c0 6.6-5.4 12-12 12H60c-6.6 0-12-5.4-12-12V60c0-6.6 5.4-12 12-12h200c6.6 0 12 5.4 12 12v312z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Im B\u00fcro der Reiseleitung sind wir gerne wie folgt f\u00fcr Sie erreichbar:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-3c5ee30 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"3c5ee30\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-8329ad1 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"8329ad1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c301a4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9c301a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Mo-Fr:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9ba6dc elementor-widget__width-initial elementor-widget elementor-widget-ae-acf\" data-id=\"f9ba6dc\" data-element_type=\"widget\" data-widget_type=\"ae-acf.text\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-acf-wrapper\">\n\t\t<div itemprop=\"name\" class=\"ae-acf-content-wrapper\">9:30 &#8211; 16:00 Uhr<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-6c118a1 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"6c118a1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-87d7422 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"87d7422\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Montag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-b548db0 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"b548db0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-f463f7e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f463f7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dienstag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-a2071fe e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"a2071fe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-70ea30e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"70ea30e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Mittwoch:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-e0e0b42 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"e0e0b42\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-ca313d5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ca313d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Donnerstag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-e4feb7d e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"e4feb7d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-2450940 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2450940\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Freitag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-5a2818f e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"5a2818f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-fc10b94 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fc10b94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">ausser:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-6537975 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"6537975\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e635236 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e635236\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Samstag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b73fe46 elementor-widget__width-initial elementor-widget elementor-widget-ae-acf\" data-id=\"b73fe46\" data-element_type=\"widget\" data-widget_type=\"ae-acf.text\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-acf-wrapper\">\n\t\t<div itemprop=\"name\" class=\"ae-acf-content-wrapper\">9:30 &#8211; 13:00 Uhr<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-233fe6e e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"233fe6e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-75a90dc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"75a90dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Sonntag:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-607364a e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"607364a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-789b398 elementor-icon-list--layout-inline emailButton elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"789b398\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/sc.ibz@dertour.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sc.ibz@dertour.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2670ba7 elementor-icon-list--layout-inline phoneButton elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2670ba7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+34%20871520219\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+34 871520219<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-099637e elementor-widget elementor-widget-heading\" data-id=\"099637e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">SOS-Nummer ausschlie\u00dflich in Notf\u00e4llen:<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7d07b elementor-icon-list--layout-inline phoneButton elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0d7d07b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+34%20647884628\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+34 647884628<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div> <!-- end .ae-outer-wrapper -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sie brauchen Hilfe oder haben Fragen? Viele Fragen versuchen wir bereits in unserem Bereich FAQ (h\u00e4ufig gestellte Fragen) zu beantworten. Wenn Sie dort die gesuchte Information nicht finden, kontaktieren Sie gerne das \u00f6rtliche Team der Reiseleitung \u00fcber das nachfolgende Formular. Bitte beachten Sie, dass die Bearbeitung nur w\u00e4hrend der B\u00fcrozeiten erfolgt. Bitte treffen Sie eine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"seitenkategorien":[],"class_list":["post-2790","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/2790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/comments?post=2790"}],"version-history":[{"count":20,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/2790\/revisions"}],"predecessor-version":[{"id":10831,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/pages\/2790\/revisions\/10831"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/media?parent=2790"}],"wp:term":[{"taxonomy":"seitenkategorien","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/ibiza\/wp-json\/wp\/v2\/seitenkategorien?post=2790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}