{"id":10224,"date":"2025-04-24T13:34:08","date_gmt":"2025-04-24T10:34:08","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/korfu\/?p=10224"},"modified":"2025-05-01T16:43:01","modified_gmt":"2025-05-01T13:43:01","slug":"muss-ich-den-mietwagen-vollgetankt-zurueckgeben","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/korfu\/faq\/rentals\/muss-ich-den-mietwagen-vollgetankt-zurueckgeben\/","title":{"rendered":"Muss ich den Mietwagen vollgetankt zur\u00fcckgeben?","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>In der Regel erhalten Sie Ihren Mietwagen vollgetankt und geben ihn auch vollgetankt zur\u00fcck. Andernfalls wird die Tankregelung im Mietvertrag vermerkt.<\/p>\n<p>Sollten Sie den Mietwagen nicht mit der vereinbarten Tankf\u00fcllung zur\u00fcckgeben, werden vom Mietwagenpartner eine Servicepauschale sowie die Kosten f\u00fcr das fehlende Benzin erhoben.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>In der Regel erhalten Sie Ihren Mietwagen vollgetankt und geben ihn auch vollgetankt zur\u00fcck. Andernfalls wird die Tankregelung im Mietvertrag vermerkt. Sollten Sie den Mietwagen nicht mit der vereinbarten Tankf\u00fcllung zur\u00fcckgeben, werden vom Mietwagenpartner eine Servicepauschale sowie die Kosten f\u00fcr das fehlende Benzin erhoben.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[194],"tags":[],"class_list":["post-10224","post","type-post","status-publish","format-standard","hentry","category-rentals","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/posts\/10224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/comments?post=10224"}],"version-history":[{"count":1,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/posts\/10224\/revisions"}],"predecessor-version":[{"id":10229,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/posts\/10224\/revisions\/10229"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/media?parent=10224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/categories?post=10224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/korfu\/wp-json\/wp\/v2\/tags?post=10224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}