{"id":2455,"date":"2025-01-08T21:25:27","date_gmt":"2025-01-08T20:25:27","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/menorca\/?page_id=2455"},"modified":"2026-04-08T16:08:08","modified_gmt":"2026-04-08T14:08:08","slug":"abreise-und-transfers","status":"publish","type":"page","link":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/abreise-und-transfers\/","title":{"rendered":"Abreise und Transfers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2455\" class=\"elementor elementor-2455\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7d74191 e-con-full e-flex ae-bg-gallery-type-default e-con e-parent\" data-id=\"7d74191\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-c5bb08a e-flex e-con-boxed ae-bg-gallery-type-default e-con e-child\" data-id=\"c5bb08a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c40fdc elementor-widget elementor-widget-text-editor\" data-id=\"5c40fdc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Liebe Reiseg\u00e4ste,<\/p><p>auch der sch\u00f6nste Aufenthalt geht einmal zu Ende.<br \/>Auf dieser Seite finden Sie alle Informationen rund um Ihren gebuchten Transfer sowie wichtige Hinweise zu Ihrer R\u00fcckreise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f898a3c e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"f898a3c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-fe99af2 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"fe99af2\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-3730719 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"3730719\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdb2faf elementor-widget__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cdb2faf\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bus\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM112 400c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm16-112c-17.67 0-32-14.33-32-32V128c0-17.67 14.33-32 32-32h256c17.67 0 32 14.33 32 32v128c0 17.67-14.33 32-32 32H128zm272 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82f4a9e elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"82f4a9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abfrage der Abholzeit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0fe879 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e0fe879\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Beachten Sie, dass die Abholzeiten erst <strong>24-48 Stunden vor Abreise<\/strong> zur Verf\u00fcgung stehen. Sollten die hier angezeigten Flugdaten nicht mit denen in Ihren Unterlagen \u00fcbereinstimmen, kontaktieren Sie uns bitte umgehend.<br \/><small><br \/>Wir \u00fcbernehmen keine Haftung f\u00fcr Transferinformationen, die Ihnen von Dritten zur Verf\u00fcgung gestellt werden.<\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-2bf25ad e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"2bf25ad\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0fb62a elementor-widget__width-inherit elementor-widget elementor-widget-shortcode\" data-id=\"a0fb62a\" data-element_type=\"widget\" id=\"ergebnis\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form method=\"post\">\r\n    <div>\r\n        <div style=\"text-align: center; margin-bottom: 10px;\">\r\n            <strong>F\u00fcr die Abfrage geben Sie bitte Ihre Vorgangsnummer ein:<\/strong><br\/>\r\n            <small>(Sie finden diese in Ihren Reiseunterlagen.)<\/small>\r\n        <\/div>\r\n        <div>\r\n            <input required type=\"text\" name=\"ClientRefNo\" placeholder=\"z.B. 100012345\" style=\"text-align: center; margin-bottom: 15px;\"\r\n                   value=\"\">\r\n        <\/div>\r\n        <input style=\"display:none\" type=\"text\" name=\"extra_var\" value=\"\"\/>\r\n        <div style=\"text-align: center;\">\r\n            <input class=\"der\" type=\"submit\" name=\"submit\" value=\"Abholzeit abfragen\">\r\n        <\/div>\r\n    <\/div>\r\n    <br \/>\r\n<\/form>\r\n\r\n\r\n<script>\r\ndocument.addEventListener(\"DOMContentLoaded\", function() {\r\n    });\r\n<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8481275 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8481275\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><small>Aufgrund unvorhersehbarer Ereignisse k\u00f6nnen sich kurzfristige \u00c4nderungen ergeben, wodurch sich auch Ihre Abholzeit \u00e4ndern kann. Bitte f\u00fchren Sie deshalb die Abfrage 12-24 Stunden vor Abreise noch einmal durch.<\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-b22c244 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"b22c244\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-323eed6 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"323eed6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bitten Sie, sich ca. 10 Minuten vor der angegebenen Abholzeit am Abholpunkt einzufinden. Die Abholzeiten sind Richtzeiten, d.h. kleine Abweichungen sind m\u00f6glich. Sollte Ihr Transferfahrzeug 15 Min. nach der angegebenen Zeit noch nicht eingetroffen sein, rufen Sie uns bitte an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-e833a4d e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"e833a4d\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f476565 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"f476565\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc5ccda elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cc5ccda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">TEL: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a991eb2 elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a991eb2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+385%2052443227\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+385 52443227<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e032270 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e032270\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Deutsch, Englisch<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-a977c3c e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"a977c3c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-2b10f0c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2b10f0c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">TEL: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-dcbc38b elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dcbc38b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-686dba1 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"686dba1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c17ffc2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c17ffc2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">SOS: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-171a137 elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"171a137\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+385%20994443355\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+385 994443355<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48571b3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"48571b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Deutsch, Englisch<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db98e70 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"db98e70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bitte vergewissern Sie sich, dass Ihre Koffer im Transferfahrzeug sind.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5da40f9 elementor-widget elementor-widget-image\" data-id=\"5da40f9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.dertour-reiseleitung.com\/wp-content\/uploads\/shape_abreise_2_mobil_grau.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-474b91a elementor-hidden-mobile e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"474b91a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-8827e8b e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"8827e8b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c17352 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5c17352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bitten Sie, sich ca. 10 Minuten vor der angegebenen Abholzeit am Abholpunkt einzufinden. Die Abholzeiten sind Richtzeiten, d.h. kleine Abweichungen sind m\u00f6glich. Sollte Ihr Transferfahrzeug 15 Min. nach der angegebenen Zeit noch nicht eingetroffen sein, rufen Sie uns bitte an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-b1c348c e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"b1c348c\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-e68b7c1 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"e68b7c1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d80689 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1d80689\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">TEL: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a3248 elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b9a3248\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+385%2052443227\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+385 52443227<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37f7cb2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"37f7cb2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Deutsch, Englisch<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-9284683 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"9284683\" data-element_type=\"container\">\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-574089e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"574089e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">TEL: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ae-visibility-hidden elementor-element elementor-element-e992605 elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e992605\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-d214490 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"d214490\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-383f0ea elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"383f0ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">SOS: <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7ea4e7 elementor-widget__width-initial phoneButton elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d7ea4e7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/+385%20994443355\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+385 994443355<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7136ab elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b7136ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Deutsch, Englisch<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57bfbe6 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"57bfbe6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bitte vergewissern Sie sich, dass Ihre Koffer im Transferfahrzeug sind.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-a97ff67 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"a97ff67\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-d69c1a9 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"d69c1a9\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-f19c251 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"f19c251\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f62d03a elementor-widget__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f62d03a\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-car\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M499.99 176h-59.87l-16.64-41.6C406.38 91.63 365.57 64 319.5 64h-127c-46.06 0-86.88 27.63-103.99 70.4L71.87 176H12.01C4.2 176-1.53 183.34.37 190.91l6 24C7.7 220.25 12.5 224 18.01 224h20.07C24.65 235.73 16 252.78 16 272v48c0 16.12 6.16 30.67 16 41.93V416c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-54.07c9.84-11.25 16-25.8 16-41.93v-48c0-19.22-8.65-36.27-22.07-48H494c5.51 0 10.31-3.75 11.64-9.09l6-24c1.89-7.57-3.84-14.91-11.65-14.91zm-352.06-17.83c7.29-18.22 24.94-30.17 44.57-30.17h127c19.63 0 37.28 11.95 44.57 30.17L384 208H128l19.93-49.83zM96 319.8c-19.2 0-32-12.76-32-31.9S76.8 256 96 256s48 28.71 48 47.85-28.8 15.95-48 15.95zm320 0c-19.2 0-48 3.19-48-15.95S396.8 256 416 256s32 12.76 32 31.9-12.8 31.9-32 31.9z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ed4a6 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"30ed4a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transferabmeldung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eb3ab7 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7eb3ab7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Sollten Sie eigenst\u00e4ndig zum Flughafen fahren wollen, bitten wir Sie freundlichst, uns dies mitzuteilen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-4e8b160 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"4e8b160\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c76f49e oew-align-center elementor-widget elementor-widget-oew-modal\" data-id=\"c76f49e\" data-element_type=\"widget\" data-widget_type=\"oew-modal.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\t<div class=\"oew-modal-button\">\r\n\t\t\t\t<a href=\"#oew-modal-c76f49e\" class=\"button\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t<span>Vom Transfer abmelden<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\r\n\t\t\r\n\t    <div id=\"oew-modal-c76f49e\" class=\"oew-modal-wrap oew-temp-styles\">\r\n\t\t\t\t\t\t<div class=\"oew-modal-container\">\r\n\t\t\t\t<div class=\"oew-modal-inner\">\r\n\t\t\t\t\t\r\n\t\t<button aria-label=\"Close this modal window\" type=\"button\" class=\"oew-modal-close oew-modal-close-inside\">\r\n\t\t\t<svg focusable=\"false\" aria-hidden=\"true\" role=\"img\" width=\"14\" height=\"14\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 512 512\" xml:space=\"preserve\">\r\n\t\t\t\t<path d=\"M505.943,6.058c-8.077-8.077-21.172-8.077-29.249,0L6.058,476.693c-8.077,8.077-8.077,21.172,0,29.249\r\n\t\t\t\t\tC10.096,509.982,15.39,512,20.683,512c5.293,0,10.586-2.019,14.625-6.059L505.943,35.306\r\n\t\t\t\t\tC514.019,27.23,514.019,14.135,505.943,6.058z\"\/>\r\n\t\t\t\t<path d=\"M505.942,476.694L35.306,6.059c-8.076-8.077-21.172-8.077-29.248,0c-8.077,8.076-8.077,21.171,0,29.248l470.636,470.636\r\n\t\t\t\t\tc4.038,4.039,9.332,6.058,14.625,6.058c5.293,0,10.587-2.019,14.624-6.057C514.018,497.866,514.018,484.771,505.942,476.694z\"\/>\r\n\t\t\t<\/svg>\r\n\t\t<\/button>\r\n\r\n\t\r\n\t\t\t\t\t<p><div class=\"frm_forms  with_frm_style frm_center_submit frm_style_der-style\" id=\"frm_form_8_container\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\">\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_ajax_submit  frm_pro_form \" id=\"form_transfer-abmeldung\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\" data-token=\"c256a7afd66f4feb3e488f17237c97b7\">\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Transfer-Abmeldung<\/legend>\r\n<h3 class=\"frm_form_title\" style=\"margin: 0px;\">Transfer-Abmeldung<\/h3>\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"8\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_8\" id=\"frm_hide_fields_8\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"transfer-abmeldung\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_8\" name=\"frm_submit_entry_8\" value=\"3291852b4c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/kroatien\/wp-json\/wp\/v2\/pages\/2455\" \/><div id=\"frm_field_134_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_qh4icy22\" id=\"field_qh4icy22_label\" class=\"frm_primary_label\">Ihre Vorgangsnummer\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy22\" name=\"item_meta[134]\" value=\"\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Name is invalid\" aria-invalid=\"false\"   aria-describedby=\"frm_desc_field_qh4icy22\" \/>\r\n    <div class=\"frm_description\" id=\"frm_desc_field_qh4icy22\">Diese finden Sie in Ihren Reiseunterlagen.<\/div>\r\n    \r\n<\/div>\n<div id=\"frm_field_135_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_jeh6f\" id=\"field_jeh6f_label\" class=\"frm_primary_label\">Ihr Name\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_jeh6f\" name=\"item_meta[135]\" value=\"\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Name is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_136_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_29yf4d22\" id=\"field_29yf4d22_label\" class=\"frm_primary_label\">Ihre E-Mail-Adresse\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_29yf4d22\" name=\"item_meta[136]\" value=\"\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"ung\u00fcltige E-Mail-Adresse\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_137_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container vertical_radio\">\r\n    <div  id=\"field_ors0g_label\" class=\"frm_primary_label\">Sollen alle Personen abgemeldet werden?\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_ors0g_label\" role=\"radiogroup\" aria-required=\"true\">\t\t<div class=\"frm_radio\" id=\"frm_radio_137-0\">\t\t\t<label  for=\"field_ors0g-0\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[137]\" id=\"field_ors0g-0\" value=\"Ja\"\n\t\t   data-reqmsg=\"Pflichtfeld\" data-invmsg=\"Sollen alle Personen abgemeldet werden? ist ung\u00fcltig\" aria-invalid=\"false\"  \/> Ja<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_137-1\">\t\t\t<label  for=\"field_ors0g-1\">\n\t\t\t\t\t<input type=\"radio\" name=\"item_meta[137]\" id=\"field_ors0g-1\" value=\"Nein\"\n\t\t   data-reqmsg=\"Pflichtfeld\" data-invmsg=\"Sollen alle Personen abgemeldet werden? ist ung\u00fcltig\" aria-invalid=\"false\"  \/> Nein<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_138_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_ysegy\" id=\"field_ysegy_label\" class=\"frm_primary_label\">Bitte geben Sie nur den\/die Namen der Person(en) ein, die abgemeldet werden sollen.\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ysegy\" name=\"item_meta[138]\" value=\"\"  data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_139_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_brxfb\" id=\"field_brxfb_label\" class=\"frm_primary_label\">Abreisedatum\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_brxfb\" name=\"item_meta[139]\" value=\"\"  maxlength=\"10\" data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"ung\u00fcltiges Datum\" class=\"frm_date\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_140_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n    <label for=\"field_kvrhl\" id=\"field_kvrhl_label\" class=\"frm_primary_label\">Flugnummer\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_kvrhl\" name=\"item_meta[140]\" value=\"\"  data-reqmsg=\"Pflichtfeld\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_141_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container vertical_radio\">\r\n    <div  id=\"field_6k3rs_label\" class=\"frm_primary_label\">DSE\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_6k3rs_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_141-0\">\t\t\t<label  for=\"field_6k3rs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[141][]\" id=\"field_6k3rs-0\" value=\"Ich habe die &lt;a href=&quot;https:\/\/dertour-reiseleitung.com\/datenschutzerklaerung\/&quot;&gt;Datenschutzerkl\u00e4rung&lt;\/a&gt; zur Kenntnis genommen. &lt;span style=&quot;color:#e40028;&quot;&gt;*&lt;\/span&gt;\"  data-reqmsg=\"Pflichtfeld\" data-invmsg=\"DSE ist ung\u00fcltig\" aria-invalid=\"false\"   aria-required=\"true\"  \/> Ich habe die <a href=\"https:\/\/dertour-reiseleitung.com\/datenschutzerklaerung\/\">Datenschutzerkl\u00e4rung<\/a> zur Kenntnis genommen. <span style=\"color:#e40028\">*<\/span><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_190_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Senden und vom Transfer abmelden<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t\t<div class=\"frm__673b936abcceb\">\n\t\t\t\t<label for=\"frm_email_8\" >\n\t\t\t\t\t&nbsp;\t\t\t\t<\/label>\n\t\t\t\t<input  id=\"frm_email_8\" type=\"email\" class=\"frm_verify\" name=\"frm__673b936abcceb\" value=\"\"  \/>\n\t\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"V+MFfHji55oRpZYOwIVjJ0g\/hRA7EeWA06e3A+M2yCM=\" \/><small>Mit dem Absenden erkl\u00e4ren Sie verbindlich, dass Sie den gebuchten Transfer am Abreisetag nicht in Anspruch nehmen werden. Durch die Abmeldung des Transfers erfolgt kein Rechtsanspruch auf eine Gutschrift dieser Leistung.<\/small>\r\n<div style=\"text-align: right;\"><small><strong><span style=\"color: #e40028;\">*<\/span><\/strong> Pflichtfeld<\/small><\/div>\r\n<br \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/p>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"oew-modal-overlay\"><\/div>\r\n\t\t<\/div>\r\n\r\n\t    \r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-44b4059 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"44b4059\" data-element_type=\"container\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-19979d3 e-con-full e-flex ae-bg-gallery-type-default e-con e-child\" data-id=\"19979d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a77285f elementor-widget__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a77285f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480 192H365.71L260.61 8.06A16.014 16.014 0 0 0 246.71 0h-65.5c-10.63 0-18.3 10.17-15.38 20.39L214.86 192H112l-43.2-57.6c-3.02-4.03-7.77-6.4-12.8-6.4H16.01C5.6 128-2.04 137.78.49 147.88L32 256 .49 364.12C-2.04 374.22 5.6 384 16.01 384H56c5.04 0 9.78-2.37 12.8-6.4L112 320h102.86l-49.03 171.6c-2.92 10.22 4.75 20.4 15.38 20.4h65.5c5.74 0 11.04-3.08 13.89-8.06L365.71 320H480c35.35 0 96-28.65 96-64s-60.65-64-96-64z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc04528 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"fc04528\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Online Check-in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3f16b3 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c3f16b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Nicht alle Fluggesellschaften bieten diesen Service an, aber bei manchen Fluggesellschaften ist er sogar erforderlich. Den Online-Check-In nehmen Sie selbst vor. In Ihren Reiseunterlagen ist f\u00fcr viele Fluggesellschaften ein QR Code f\u00fcr den Online Check-In hinterlegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-c6f22d3 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"c6f22d3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5314511 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"5314511\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ An- und Abreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ab3ee3 elementor-widget__width-initial acc-faq elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ae-post-blocks-adv\" data-id=\"8ab3ee3\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_accordion_state&quot;:&quot;all_closed&quot;}\" data-widget_type=\"ae-post-blocks-adv.accordion\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"ae-outer-wrapper ae-height-100\" >\n\n\t\t\t\n\t\t\t<div class=\"ae-post-collection elementor-accordion ae-accordion\" role=\"tablist\" data-transition-speed=\"300\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-11822306061\" t_id=\"11822306061\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tab\" aria-controls=\"ae-tab-content-11822306061\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Regelungen gelten f\u00fcr das Handgep\u00e4ck im Flugzeug?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-11822306061\" t_id=\"11822306061\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-11822306061\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8ab3ee3\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tF\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt. Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck: Reisende d\u00fcrfen Fl\u00fcssigkeiten nur in Beh\u00e4ltern mitnehmen, deren Fassungsverm\u00f6gen maximal 100 ml betr\u00e4gt. Alle Fl\u00fcssigkeitsbeh\u00e4lter m\u00fcssen in einem Plastikbeutel (maximales Fassungsverm\u00f6gen: 1 l) an den Sicherheitskontrollstellen vorgezeigt werden. Dieser muss transparent und verschlie\u00dfbar sein. Es besteht f\u00fcr die Flugh\u00e4fen keine Pflicht, Plastikbeutel f\u00fcr die Reisenden...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-11822306062\" t_id=\"11822306062\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tab\" aria-controls=\"ae-tab-content-11822306062\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise aus einem Nicht-EU-Land?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-11822306062\" t_id=\"11822306062\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-11822306062\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8ab3ee3\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tNeben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren: Tabakwaren Wenn Sie mindestens 17 Jahre alt sind: 200 Zigaretten oder 100 Zigarillos oder 50 Zigarren oder 250 g Rauchtabak oder eine anteilige Zusammenstellung der Rauchwaren. Alkohol und alkoholhaltige Getr\u00e4nke Wenn Sie mindestens 17 Jahre alt sind: 1 l Spirituosen mit einem Alkoholgehalt von mehr als 22 % Vol. oder 1 l unverg\u00e4llter Ethylalkohol mit einem Alkoholgehalt von 80 % Vol....\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-11822306063\" t_id=\"11822306063\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tab\" aria-controls=\"ae-tab-content-11822306063\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise in die Schweiz?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-11822306063\" t_id=\"11822306063\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-11822306063\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8ab3ee3\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tEinfuhr von Waren durch Privatpersonen Generell gilt eine Freigrenze von 150 SFr bei Waren f\u00fcr den privaten Gebrauch, die pers\u00f6nlich im Reiseverkehr eingef\u00fchrt werden. Liegt der Gesamtwert der mitgef\u00fchrten Waren \u00fcber 150 SFr, so sind alle Waren abgabenpflichtig. Freimengen und -grenzen werden nur einmal pro Person und Tag gew\u00e4hrt. Es gelten folgende Freimengen: Alkoholische Getr\u00e4nke Personen ab 17 Jahren d\u00fcrfen einmal pro Tag abgabenfrei folgende Mengen einf\u00fchren: 5 l alkoholische Getr\u00e4nke bis 18 % Vol. und 1 l \u00fcber 18 % Vol. einf\u00fchren. Dar\u00fcber hinaus gelten folgende Zollabgaben: Alkoholische Getr\u00e4nke bis 18 % Vol.: 2 SFr\/l Alkoholische Getr\u00e4nke \u00fcber 18...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-in-die-schweiz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-11822306064\" t_id=\"11822306064\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tab\" aria-controls=\"ae-tab-content-11822306064\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei Reisen innerhalb der EU?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-11822306064\" t_id=\"11822306064\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-11822306064\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8ab3ee3\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tGrunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen: Parfum: Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist. Arzneimittel: Nur f\u00fcr den pers\u00f6nlichen Bedarf. Kaffee: 10 kg Alkoholische Getr\u00e4nke: 10 l Spirituosen 10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops) 20 l Lik\u00f6rwein, Wermutwein 90 l Wein (davon h\u00f6chstens 60 l Schaumwein) 110 l Bier Bei der Einreise nach Deutschland: Tabakwaren: 800 Zigaretten oder 400 Zigarillos oder 200 Zigarren oder 1 kg Rauchtabak Bei der Einreise nach \u00d6sterreich: F\u00fcr die private Einfuhr von Tabakerzeugnissen nach \u00d6sterreich gilt: Tabakwaren, die im Ausland erworben...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div> <!-- end .ae-outer-wrapper -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af9ac8e elementor-widget elementor-widget-image\" data-id=\"af9ac8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.dertour-reiseleitung.com\/wp-content\/uploads\/shape_reiseleitung_1_mobil_grau.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-a580f5b e-con-full elementor-hidden-mobile e-flex ae-bg-gallery-type-default e-con e-parent\" data-id=\"a580f5b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"has_ae_slider elementor-element elementor-element-6a93d5e e-flex e-con-boxed ae-bg-gallery-type-default e-con e-child\" data-id=\"6a93d5e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5609a53 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"5609a53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ An- und Abreise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a9cdf6 elementor-widget__width-initial acc-faq elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ae-post-blocks-adv\" data-id=\"8a9cdf6\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_accordion_state&quot;:&quot;all_closed&quot;}\" data-widget_type=\"ae-post-blocks-adv.accordion\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"ae-outer-wrapper ae-height-100\" >\n\n\t\t\t\n\t\t\t<div class=\"ae-post-collection elementor-accordion ae-accordion\" role=\"tablist\" data-transition-speed=\"300\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-33533168751\" t_id=\"33533168751\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tab\" aria-controls=\"ae-tab-content-33533168751\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Regelungen gelten f\u00fcr das Handgep\u00e4ck im Flugzeug?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-33533168751\" t_id=\"33533168751\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-33533168751\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8a9cdf6\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tF\u00fcr alle Abfl\u00fcge von Flugh\u00e4fen innerhalb der Europ\u00e4ischen Gemeinschaft und seit dem 1. M\u00e4rz 2009 auch der T\u00fcrkei gilt die Verordnung der Europ\u00e4ischen Kommission zur Sicherheit des zivilen Luftverkehrs. Durch diese Verordnung wird die Menge an Fl\u00fcssigkeit, die Reisende im Handgep\u00e4ck durch die Sicherheitskontrollstellen mitnehmen d\u00fcrfen, beschr\u00e4nkt. Es gibt zwei Einschr\u00e4nkungen der Fl\u00fcssigkeitsmengen im Handgep\u00e4ck: Reisende d\u00fcrfen Fl\u00fcssigkeiten nur in Beh\u00e4ltern mitnehmen, deren Fassungsverm\u00f6gen maximal 100 ml betr\u00e4gt. Alle Fl\u00fcssigkeitsbeh\u00e4lter m\u00fcssen in einem Plastikbeutel (maximales Fassungsverm\u00f6gen: 1 l) an den Sicherheitskontrollstellen vorgezeigt werden. Dieser muss transparent und verschlie\u00dfbar sein. Es besteht f\u00fcr die Flugh\u00e4fen keine Pflicht, Plastikbeutel f\u00fcr die Reisenden...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-regelungen-gelten-fuer-das-handgepaeck-im-flugzeug\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-33533168752\" t_id=\"33533168752\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tab\" aria-controls=\"ae-tab-content-33533168752\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise aus einem Nicht-EU-Land?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-33533168752\" t_id=\"33533168752\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-33533168752\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8a9cdf6\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tNeben den Waren, die Sie auf Ihrer Reise aus Deutschland, \u00d6sterreich und den Niederlanden mitgenommen haben und als sogenannte R\u00fcckwaren wieder einf\u00fchren, bleiben als Reisemitbringsel folgende Waren einfuhrabgabenfrei, sofern Sie diese ausschlie\u00dflich zum pers\u00f6nlichen Gebrauch oder als Geschenk einf\u00fchren: Tabakwaren Wenn Sie mindestens 17 Jahre alt sind: 200 Zigaretten oder 100 Zigarillos oder 50 Zigarren oder 250 g Rauchtabak oder eine anteilige Zusammenstellung der Rauchwaren. Alkohol und alkoholhaltige Getr\u00e4nke Wenn Sie mindestens 17 Jahre alt sind: 1 l Spirituosen mit einem Alkoholgehalt von mehr als 22 % Vol. oder 1 l unverg\u00e4llter Ethylalkohol mit einem Alkoholgehalt von 80 % Vol....\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-aus-einem-nicht-eu-land\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-33533168753\" t_id=\"33533168753\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tab\" aria-controls=\"ae-tab-content-33533168753\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei der Einreise in die Schweiz?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-33533168753\" t_id=\"33533168753\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-33533168753\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8a9cdf6\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tEinfuhr von Waren durch Privatpersonen Generell gilt eine Freigrenze von 150 SFr bei Waren f\u00fcr den privaten Gebrauch, die pers\u00f6nlich im Reiseverkehr eingef\u00fchrt werden. Liegt der Gesamtwert der mitgef\u00fchrten Waren \u00fcber 150 SFr, so sind alle Waren abgabenpflichtig. Freimengen und -grenzen werden nur einmal pro Person und Tag gew\u00e4hrt. Es gelten folgende Freimengen: Alkoholische Getr\u00e4nke Personen ab 17 Jahren d\u00fcrfen einmal pro Tag abgabenfrei folgende Mengen einf\u00fchren: 5 l alkoholische Getr\u00e4nke bis 18 % Vol. und 1 l \u00fcber 18 % Vol. einf\u00fchren. Dar\u00fcber hinaus gelten folgende Zollabgaben: Alkoholische Getr\u00e4nke bis 18 % Vol.: 2 SFr\/l Alkoholische Getr\u00e4nke \u00fcber 18...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-der-einreise-in-die-schweiz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-accordion-item\">\n\t\t\t\t\t\t\t<div id=\"ae-tab-title-33533168754\" t_id=\"33533168754\" class=\"ae-tab-title ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tab\" aria-controls=\"ae-tab-content-33533168754\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon ae-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"ae-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">Welche Zollfreigrenzen gelten bei Reisen innerhalb der EU?<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"ae-tab-content-33533168754\" t_id=\"33533168754\" class=\"elementor-clearfix ae-tab-content ae-post-blocks-adv-accordion\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ae-tab-title-33533168754\">\n\t\t\t\t\t\t\n\t\t<article class=\"ae-post-item ae-post-item-8a9cdf6\" >\n\t\t\t<div class=\"ae-post-item-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-4187\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4187\" class=\"elementor elementor-4187\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t<div class=\"has_ae_slider elementor-element elementor-element-7ff9138 e-flex e-con-boxed ae-bg-gallery-type-default e-con e-parent\" data-id=\"7ff9138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed5c6e elementor-widget elementor-widget-ae-post-content\" data-id=\"5ed5c6e\" data-element_type=\"widget\" data-widget_type=\"ae-post-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ae-element-post-content\">\n\t\t\t\t\t\t\tGrunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen: Parfum: Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist. Arzneimittel: Nur f\u00fcr den pers\u00f6nlichen Bedarf. Kaffee: 10 kg Alkoholische Getr\u00e4nke: 10 l Spirituosen 10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops) 20 l Lik\u00f6rwein, Wermutwein 90 l Wein (davon h\u00f6chstens 60 l Schaumwein) 110 l Bier Bei der Einreise nach Deutschland: Tabakwaren: 800 Zigaretten oder 400 Zigarillos oder 200 Zigarren oder 1 kg Rauchtabak Bei der Einreise nach \u00d6sterreich: F\u00fcr die private Einfuhr von Tabakerzeugnissen nach \u00d6sterreich gilt: Tabakwaren, die im Ausland erworben...\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f3959 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"03f3959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dertour-reiseleitung.com\/kroatien\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div> <!-- end .ae-outer-wrapper -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Liebe Reiseg\u00e4ste, auch der sch\u00f6nste Aufenthalt geht einmal zu Ende.Auf dieser Seite finden Sie alle Informationen rund um Ihren gebuchten Transfer sowie wichtige Hinweise zu Ihrer R\u00fcckreise. Abfrage der Abholzeit Beachten Sie, dass die Abholzeiten erst 24-48 Stunden vor Abreise zur Verf\u00fcgung stehen. Sollten die hier angezeigten Flugdaten nicht mit denen in Ihren Unterlagen \u00fcbereinstimmen, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"Abreise &amp; Transfers","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":8920,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"seitenkategorien":[],"class_list":["post-2455","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/pages\/2455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/comments?post=2455"}],"version-history":[{"count":20,"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/pages\/2455\/revisions"}],"predecessor-version":[{"id":10434,"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/pages\/2455\/revisions\/10434"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/media?parent=2455"}],"wp:term":[{"taxonomy":"seitenkategorien","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/kroatien\/wp-json\/wp\/v2\/seitenkategorien?post=2455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}