{"id":9366,"date":"2025-03-17T14:05:17","date_gmt":"2025-03-17T14:05:17","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/uncategorized\/schwimmen-und-baden-im-hotelpool\/"},"modified":"2025-09-25T13:50:18","modified_gmt":"2025-09-25T12:50:18","slug":"schwimmen-und-baden-im-hotelpool","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/sicherheitshinweise\/schwimmen-und-baden-im-hotelpool\/","title":{"rendered":"Schwimmen und Baden im Hotelpool","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Gerade der Poolbereich ist im Urlaub ein besonderes Highlight f\u00fcr Ihre Kinder. Den ganzen Tag bei wunderbarem Wetter im Wasser zu toben und zu spielen, ist ein Urlaubserlebnis, an das sich Ihre Kinder gerne zur\u00fcckerinnern werden.<\/p>\n<p>Die gewaltigen Wassermassen eines Hotelpools nach gesundheitlichen Richtlinien sauber zu halten, erfordert allerdings aufwendige Technik. Gerade in Bereichen der Wasserattraktionen und Rutschen erbringen die Pool-Pumpen oft H\u00f6chstleistungen. Hier ist es besonders wichtig, dass Sie Ihre Kinder vor der Benutzung darauf hinweisen, gen\u00fcgend Abstand zu den Ansauggittern zu halten und im Falle eines losen Gitters auf keinen Fall hineinzugreifen.<\/p>\n<p>Haben Sie oder Ihre Kinder eine Gefahrenquelle im Hotelpool festgestellt, informieren Sie bitte umgehend das Hotelpersonal, damit es sich um die Beseitigung k\u00fcmmern kann. Bitte informieren Sie auch Ihre Reiseleitung vor Ort. Sie wird die ordnungsgem\u00e4\u00dfe Behebung der Gefahrenquelle \u00fcberpr\u00fcfen. Unabh\u00e4ngig davon sollten zwecks Unfallvermeidung folgende Verhaltensregeln beachtet werden:<\/p>\n<ul class=\"square\">\n<li>Nutzen Sie den Pool nur zu den offiziellen Benutzungszeiten.<\/li>\n<li>Beachten Sie bitte die Baderegeln und erkl\u00e4ren Sie diese auch Ihren Kindern.<\/li>\n<li>Lassen Sie Ihre Kinder am und im Pool nicht unbeaufsichtigt, da nicht in jedem Land\/Hotel Rettungsschwimmer am Pool sind.<\/li>\n<li>Machen Sie keine Kopfspr\u00fcnge in weniger als 1,50 m tiefes Wasser.<\/li>\n<li>Treten Sie bitte nicht auf die Plastik-\u00dcberlaufrinnen am Beckenrand, da diese bei einer pl\u00f6tzlichen Belastung einbrechen k\u00f6nnen.<\/li>\n<li>Aufgrund der dauerhaften Belastung durch Wasser k\u00f6nnen sich gelegentlich Fliesen im Pool l\u00f6sen. Achten Sie darauf beim Betreten des Pools und informieren Sie bitte sofort das Hotelpersonal, sollten Sie lose Fliesen entdeckt haben.<\/li>\n<li>Im Falle einer vorhandenen Rutsche: Bitte fordern Sie Ihre Kinder auf, das Auffangbecken bzw. den Beckenbereich direkt nach dem Auftauchen aus dem Wasser zu verlassen und nicht zum Schwimmen oder Spielen aufzusuchen.<\/li>\n<li>Achten Sie auf die Tiefenangaben am Seitenrand, um nicht unvorbereitet vom Nichtschwimmer- in den Schwimmerbereich zu gelangen.<\/li>\n<li>Bitte beachten Sie am Pool und an den Rutschen die aufgef\u00fchrten Piktogramme und Hinweise zur Benutzung und zur Wassertiefe.<\/li>\n<\/ul>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Gerade der Poolbereich ist im Urlaub ein besonderes Highlight f\u00fcr Ihre Kinder. Den ganzen Tag bei wunderbarem Wetter im Wasser zu toben und zu spielen, ist ein Urlaubserlebnis, an das sich Ihre Kinder gerne zur\u00fcckerinnern werden. Die gewaltigen Wassermassen eines Hotelpools nach gesundheitlichen Richtlinien sauber zu halten, erfordert allerdings aufwendige Technik. Gerade in Bereichen der [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":4,"featured_media":9367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-9366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sicherheitshinweise","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/comments?post=9366"}],"version-history":[{"count":2,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9366\/revisions"}],"predecessor-version":[{"id":11075,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9366\/revisions\/11075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/media\/9367"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/media?parent=9366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/categories?post=9366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/tags?post=9366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}