{"id":9408,"date":"2025-03-17T14:05:17","date_gmt":"2025-03-17T14:05:17","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/uncategorized\/playa-blanca\/"},"modified":"2025-09-25T13:50:09","modified_gmt":"2025-09-25T12:50:09","slug":"playa-blanca","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/infos-a-z\/orte-infos-a-z\/playa-blanca\/","title":{"rendered":"Playa Blanca","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<h3>Das Tor nach Fuerteventura<\/h3>\n<p>Das ehemalige Fischerdorf Playa Blanca (deutsch: wei\u00dfer Strand) ist heute ein Touristenzentrum im S\u00fcden Lanzarotes und geh\u00f6rt zur Gemeinde Yaiza. Entlang der K\u00fcste f\u00fchrt eine sch\u00f6ne Promenade, von der aus Sie einen atemberaubenden Ausblick auf die Nachbarinsel Fuerteventura mit ihren strahlend wei\u00dfen D\u00fcnen haben. Hier befinden sich auch zahlreiche Restaurants und Bars sowie etliche Gesch\u00e4fte. Vom F\u00e4hrhafen der Stadt gibt es t\u00e4glich zahlreiche F\u00e4hrverbindungen der Reedereien Fred Olsen Express und Naviera Armas nach Corralejo auf der Nachbarinsel Fuerteventura. Die \u00dcberfahrt dauert etwa eine halbe Stunde.<\/p>\n<p>Folgen Sie der Promenade weiter Richtung Osten, erreichen Sie den neuen Yachthafen Marina Rubicon. Hier finden sich weitere Restaurants und Freizeiteinrichtungen.<\/p>\n<p>Nord\u00f6stlich des Ortes liegen die Papagayo-Str\u00e4nde: mehrere Badebuchten, die mit kristallklarem Wasser und hellen Str\u00e4nden locken. Drei Kilometer westlich von Playa Blanca kommt man zum 194 Meter hohen roten Aschevulkan Monta\u00f1a Roja, auf den auch ein Wanderweg hinauff\u00fchrt. Weiter geht es in dieser Richtung zum alten, 1936 errichteten Fischerleuchtturm Faro de Pechiguera. Er markiert den s\u00fcdwestlichsten Punkt Lanzarotes. Der h\u00f6here Leuchtturm, der direkt daneben steht, wurde 1986 erbaut.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Das Tor nach Fuerteventura Das ehemalige Fischerdorf Playa Blanca (deutsch: wei\u00dfer Strand) ist heute ein Touristenzentrum im S\u00fcden Lanzarotes und geh\u00f6rt zur Gemeinde Yaiza. Entlang der K\u00fcste f\u00fchrt eine sch\u00f6ne Promenade, von der aus Sie einen atemberaubenden Ausblick auf die Nachbarinsel Fuerteventura mit ihren strahlend wei\u00dfen D\u00fcnen haben. Hier befinden sich auch zahlreiche Restaurants und [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":4,"featured_media":9409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[46],"tags":[],"class_list":["post-9408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orte-infos-a-z","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/comments?post=9408"}],"version-history":[{"count":2,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9408\/revisions"}],"predecessor-version":[{"id":11074,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/posts\/9408\/revisions\/11074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/media\/9409"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/media?parent=9408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/categories?post=9408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/lanzarote\/wp-json\/wp\/v2\/tags?post=9408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}