{"id":10067,"date":"2025-04-15T14:16:04","date_gmt":"2025-04-15T13:16:04","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/madeira\/?post_type=product&#038;p=10067"},"modified":"2026-03-10T15:44:42","modified_gmt":"2026-03-10T14:44:42","slug":"kombi-expedition-santana-levada-und-jeep-safari-dds-004-2","status":"publish","type":"product","link":"https:\/\/www.dertour-reiseleitung.com\/madeira\/aktivitaeten\/kombi-expedition-santana-levada-und-jeep-safari-dds-004-2\/","title":{"rendered":"Kombi Expedition Santana \u2013 Levada und Jeep-Safari"},"content":{"rendered":"<h3>Wanderung durch Madeiras Naturparadies<\/h3>\n<p>Eine wilde Expedition, die eine Jeep-Safari mit leichten Levada-Wanderungen kombiniert.<\/p>\n<p>Besuchen Sie den dritth\u00f6chsten Berg, den Pico do Arieiro, mit dem Gel\u00e4ndewagen. Sie erleben den Laurisilva-Wald bei Ribeiro Frio mit erstaunlichen Aussichten \u00fcber Berge und T\u00e4ler und einem fernen blauen Meer im Hintergrund.<\/p>\n<p>\u00dcberqueren Sie die Berge mit dem Gel\u00e4ndewagen, bis Sie das wilde Nordmeer bei Porto da Cruz erreichen. Machen Sie einen Spaziergang entlang einer &#8222;Levada&#8220;, einem der vielen Bew\u00e4sserungskan\u00e4le, die unser Land bew\u00e4ssern. Fahren Sie an die \u00e4u\u00dferste Ostseite der Insel, nach Porta de S\u00e3o Louren\u00e7o in Cani\u00e7al.<\/p>\n<p>Ein herrlich abwechslungsreicher Tag mit sch\u00f6nen Aussichtspunkten und kleinen Fussm\u00e4rschen. Abwechslung und Spass f\u00fcr die ganze Familie!<\/p>\n<p><strong>Ausflugsveranstalter: <\/strong>MTS \u2013 Mediterranean Travel Services Incoming Portugal, S.A.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wanderung durch Madeiras Naturparadies Eine wilde Expedition, die eine Jeep-Safari mit leichten Levada-Wanderungen kombiniert. Besuchen Sie den dritth\u00f6chsten Berg, den Pico do Arieiro, mit dem Gel\u00e4ndewagen. Sie erleben den Laurisilva-Wald bei Ribeiro Frio mit erstaunlichen Aussichten \u00fcber Berge und T\u00e4ler und einem fernen blauen Meer im Hintergrund. \u00dcberqueren Sie die Berge mit dem Gel\u00e4ndewagen, bis [&hellip;]<\/p>\n","protected":false},"featured_media":9884,"template":"","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":11202,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":""},"ort":[465,461],"sichtbarkeit":[],"templateoption":[179],"product_brand":[],"product_cat":[182],"product_tag":[],"class_list":{"0":"post-10067","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ort-machico","7":"ort-ponta-do-sol","8":"templateoption-dertrip-bc","9":"product_cat-ausfluege","11":"entry","12":"has-media","14":"first","15":"instock","16":"virtual","17":"purchasable","18":"product-type-simple","19":"has-product-nav","20":"col","21":"span_1_of_3","22":"owp-content-center","23":"owp-thumbs-layout-horizontal","24":"owp-btn-normal","25":"owp-tabs-layout-section","26":"has-no-thumbnails"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product\/10067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":14,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product\/10067\/revisions"}],"predecessor-version":[{"id":12676,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product\/10067\/revisions\/12676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/media\/9884"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/media?parent=10067"}],"wp:term":[{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/ort?post=10067"},{"taxonomy":"sichtbarkeit","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/sichtbarkeit?post=10067"},{"taxonomy":"templateoption","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/templateoption?post=10067"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product_brand?post=10067"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product_cat?post=10067"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/madeira\/wp-json\/wp\/v2\/product_tag?post=10067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}