{"id":740,"date":"2024-12-02T21:40:24","date_gmt":"2024-12-02T20:40:24","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/mallorca\/uncategorized\/zollinformation-innerhalb-der-eu\/"},"modified":"2025-07-18T10:38:45","modified_gmt":"2025-07-18T08:38:45","slug":"welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/faq\/an-und-abreise-faq\/welche-zollfreigrenzen-gelten-bei-reisen-innerhalb-der-eu\/","title":{"rendered":"Welche Zollfreigrenzen gelten bei Reisen innerhalb der EU?","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Grunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen:<\/p>\n<p><strong>Parfum:<\/strong> Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist.<br \/>\n<strong>Arzneimittel:<\/strong> Nur f\u00fcr den pers\u00f6nlichen Bedarf.<br \/>\n<strong>Kaffee:<\/strong> 10 kg<\/p>\n<p><strong>Alkoholische Getr\u00e4nke:<\/strong><\/p>\n<ul class=\"square\">\n<li>10 l Spirituosen<\/li>\n<li>10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops)<\/li>\n<li>20 l Lik\u00f6rwein, Wermutwein<\/li>\n<li>90 l Wein (davon h\u00f6chstens 60 l Schaumwein)<\/li>\n<li>110 l Bier<\/li>\n<\/ul>\n<h3>Bei der Einreise nach Deutschland:<\/h3>\n<p><strong>Tabakwaren:<\/strong><\/p>\n<ul class=\"square\">\n<li>800 Zigaretten oder<\/li>\n<li>400 Zigarillos oder<\/li>\n<li>200 Zigarren oder<\/li>\n<li>1 kg Rauchtabak<\/li>\n<\/ul>\n<h3>Bei der Einreise nach \u00d6sterreich:<\/h3>\n<p>F\u00fcr die private Einfuhr von Tabakerzeugnissen nach \u00d6sterreich gilt: Tabakwaren, die im Ausland erworben wurden und keine nach dem Tabakgesetz erforderlichen Warnhinweise in deutscher Sprache besitzen, d\u00fcrfen nur in beschr\u00e4nktem Umfang nach \u00d6sterreich verbracht werden.<\/p>\n<p><strong>Hier sind folgende Richtmengen zu beachten:<\/strong><\/p>\n<ul class=\"square\">\n<li>200 Zigaretten oder<\/li>\n<li>100 Zigarillos oder<\/li>\n<li>50 Zigarren oder<\/li>\n<li>250 g Rauchtabak<\/li>\n<\/ul>\n<p><strong>Generell gilt (f\u00fcr Deutschland und \u00d6sterreich):<\/strong><br \/>\nAus-\/Einfuhrberechtigt sind Personen ab 17 Jahren (f\u00fcr Kaffee ab 15 Jahren). Waren, die im Duty-free-Shop erworben werden, sind im Rahmen der oben aufgef\u00fchrten Mengen abgabefrei.<\/p>\n<p>\u00c4nderungen vorbehalten. Angaben ohne Gew\u00e4hr.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Grunds\u00e4tzlich sind alle Reisemitbringsel abgabefrei, die im Kauf-Mitgliedstaat versteuert erworben wurden. F\u00fcr den privaten Warenverkehr gelten folgende Richtmengen: Parfum: Keine Beschr\u00e4nkungen, wenn es f\u00fcr den pers\u00f6nlichen Verbrauch bestimmt ist. Arzneimittel: Nur f\u00fcr den pers\u00f6nlichen Bedarf. Kaffee: 10 kg Alkoholische Getr\u00e4nke: 10 l Spirituosen 10 l alkoholhaltige S\u00fc\u00dfgetr\u00e4nke (Alkopops) 20 l Lik\u00f6rwein, Wermutwein 90 l Wein [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[192],"tags":[],"class_list":["post-740","post","type-post","status-publish","format-standard","hentry","category-an-und-abreise-faq","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/posts\/740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/comments?post=740"}],"version-history":[{"count":7,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/posts\/740\/revisions"}],"predecessor-version":[{"id":12119,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/posts\/740\/revisions\/12119"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/media?parent=740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/categories?post=740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/mallorca\/wp-json\/wp\/v2\/tags?post=740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}