{"id":9405,"date":"2025-03-26T09:02:14","date_gmt":"2025-03-26T08:02:14","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/menorca\/uncategorized\/naturgewalten-2\/"},"modified":"2025-09-25T12:07:32","modified_gmt":"2025-09-25T10:07:32","slug":"naturgewalten-2","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/menorca\/sicherheitshinweise\/naturgewalten-2\/","title":{"rendered":"Naturgewalten","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<ul class=\"square\">\n<li>Erdbeben treten pl\u00f6tzlich, heftig und unerwartet auf. Es gibt keine M\u00f6glichkeit der Vorhersage und Fr\u00fchwarnung!<\/li>\n<li>Wenn Sie sich im Falle eines Erdbebens im Freien aufhalten, suchen Sie schnellstm\u00f6glich einen freien Platz auf, entfernt von Geb\u00e4uden, Stra\u00dfenlampen und Versorgungsleitungen.<\/li>\n<li>Sollten Sie sich w\u00e4hrend des Bebens in einem Geb\u00e4ude aufhalten, suchen Sie Schutz unter einem schweren stabilen M\u00f6belst\u00fcck \u2013 z.B. einem Tisch. Sollte kein geeignetes M\u00f6belst\u00fcck vorhanden sein, begeben Sie sich in einen T\u00fcrrahmen. Halten Sie sich fest, solange die Ersch\u00fctterung andauert. Sch\u00fctzen Sie Kopf und Gesicht mit verschr\u00e4nkten Armen.<\/li>\n<li>Bei Erdst\u00f6\u00dfen an einer flachen K\u00fcste kann ein Tsunami ausgel\u00f6st werden. Laufen Sie bitte schnellstm\u00f6glich landeinw\u00e4rts auf ein h\u00f6heres Niveau. Verlassen Sie Ihren erh\u00f6hten Zufluchtsort erst, wenn offiziell Tsunami-Entwarnung gegeben wird.<\/li>\n<\/ul>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Erdbeben treten pl\u00f6tzlich, heftig und unerwartet auf. Es gibt keine M\u00f6glichkeit der Vorhersage und Fr\u00fchwarnung! Wenn Sie sich im Falle eines Erdbebens im Freien aufhalten, suchen Sie schnellstm\u00f6glich einen freien Platz auf, entfernt von Geb\u00e4uden, Stra\u00dfenlampen und Versorgungsleitungen. Sollten Sie sich w\u00e4hrend des Bebens in einem Geb\u00e4ude aufhalten, suchen Sie Schutz unter einem schweren stabilen [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":2,"featured_media":9407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-9405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sicherheitshinweise","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/posts\/9405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/comments?post=9405"}],"version-history":[{"count":2,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/posts\/9405\/revisions"}],"predecessor-version":[{"id":9923,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/posts\/9405\/revisions\/9923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/media\/9407"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/media?parent=9405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/categories?post=9405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/menorca\/wp-json\/wp\/v2\/tags?post=9405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}