{"id":9370,"date":"2025-03-23T19:26:15","date_gmt":"2025-03-23T18:26:15","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/uncategorized\/im-hotelbereich\/"},"modified":"2025-10-06T10:36:16","modified_gmt":"2025-10-06T15:36:16","slug":"im-hotelbereich","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/sicherheitshinweise\/im-hotelbereich\/","title":{"rendered":"Im Hotelbereich","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<ul class=\"square\">\n<li>Bitte machen Sie sich mit den Fluchtwegen f\u00fcr Notf\u00e4lle in Ihrem Hotelzimmer sowie den Notrufeinrichtungen vertraut. Gerade bei mehrst\u00f6ckigen H\u00e4usern ist h\u00e4ufig kein direkter Zugang ins Freie gegeben.<\/li>\n<li>Dies gilt auch f\u00fcr h\u00e4ufig etwas abgelegene Hotelbereiche, wie z.B. Wellness-, Indoor-Sport-Bereich und Disco.<\/li>\n<li>Achten Sie auf die vorhandenen Feuerl\u00f6scher und Erste-Hilfe-K\u00e4sten und merken Sie sich deren Position.<\/li>\n<li>Bitte nehmen Sie im Notfall die Fluchtwege und nicht den Aufzug.<\/li>\n<li>Die Fluchtwege sind h\u00e4ufig nur mit einer Notbeleuchtung ausgestattet. Seien Sie deshalb bitte besonders vorsichtig beim Betreten dieser Wege, um Unf\u00e4lle zu vermeiden.<\/li>\n<li>Das gilt ebenfalls f\u00fcr Hotelbereiche wie Wellness- und Indoor-Sport-Bereiche. Ged\u00e4mpftes Licht kann die \u00dcbersicht beeintr\u00e4chtigen.<\/li>\n<li>Lassen Sie generell Ihre Kinder nicht ohne die Begleitung eines Erwachsenen mit dem Aufzug fahren. Kontrollieren Sie die ordnungsgem\u00e4\u00dfe Funktionst\u00fcchtigkeit der Lichtschranke bei selbstschlie\u00dfenden Aufzugt\u00fcren und informieren Sie sich vor Benutzung \u00fcber die allgemeinen Nutzungshinweise.<\/li>\n<li>Nicht alle Dreht\u00fcren haben Sicherheitsstopper. Bitte gehen Sie immer gemeinsam mit Ihren Kindern durch die Dreht\u00fcr.<\/li>\n<li>Achten Sie auf Fenster, Glast\u00fcren und Vitrinen! Diese sind bei starker Sonneneinstrahlung h\u00e4ufig nicht zu sehen. Es besteht erh\u00f6hte Verletzungsgefahr, da Sicherheitsglas nicht in allen L\u00e4ndern Pflicht ist.<\/li>\n<li>Seien Sie besonders vorsichtig bei einem n\u00e4chtlichen Spaziergang in der Hotelanlage. Manche Unebenheiten, die bei Tag leicht zu erkennen sind, k\u00f6nnen in der Nacht \u2013 besonders bei unbeleuchteten Gr\u00fcnanlagen \u2013 zu Stolperfallen werden.<\/li>\n<li>Aber auch am Tage k\u00f6nnen aufgrund besonderer Lichtverh\u00e4ltnisse schnell Unebenheiten und Bodenl\u00f6cher \u00fcbersehen werden. Deshalb bitten wir Sie auch hier, aufmerksam zu sein.<\/li>\n<li>In manchen Regionen sind Gel\u00e4nder und Handl\u00e4ufe aufgrund landestypischer Bauweise nicht vorgesehen. Seien Sie besonders vorsichtig beim Benutzen entsprechender Treppen.<\/li>\n<li>Bitte seien Sie stets vorsichtig bei der Benutzung Ihres Badezimmers: Durch Feuchtigkeit entsteht Rutschgefahr! Benutzen Sie keine elektronischen Ger\u00e4te, wenn Sie sich in der N\u00e4he von Wasser aufhalten.<\/li>\n<li>Achten Sie im Falle einer vorhandenen Flambierstation oder eines Show-Cooking-Bereichs darauf, dass Sie einen Abstand von mindestens einem Meter w\u00e4hrend der Zubereitung von Speisen einhalten.<\/li>\n<li>Sind Indoor-Sporteinrichtungen in Ihrem Hotel vorhanden, bitten wir Sie, generell den Anweisungen des Hotelpersonals Folge zu leisten. Bitte \u00fcberpr\u00fcfen Sie diese Einrichtungen vor der Benutzung auf ihren ordnungsgem\u00e4\u00dfen Zustand und Ihre Funktionst\u00fcchtigkeit.<\/li>\n<li>Haben Sie Fragen zur korrekten Bedienung einzelner Fitnessger\u00e4te, z\u00f6gern Sie nicht, das Hotelpersonal anzusprechen.<\/li>\n<li>Es ist uns sehr wichtig, dass Sie besonders im Wellnessbereich die gew\u00fcnschte Erholung, Entspannung und Ruhe finden. Bitte informieren Sie sich \u00fcber die Hausordnung beim Hotelpersonal.<\/li>\n<li>Begleiten Sie Ihre Kinder immer zu den Spielpl\u00e4tzen und lassen Sie sie dort nicht unbeaufsichtigt.<\/li>\n<li>Wir bitten Sie, sich vor der Benutzung von K\u00fccheneinrichtungen und -utensilien mit den Bedienungsanleitungen vertraut zu machen. Bitte \u00fcberpr\u00fcfen Sie dar\u00fcber hinaus den Zustand s\u00e4mtlicher elektronischer Ger\u00e4te und Kabel auf Unversehrtheit.<\/li>\n<\/ul>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Bitte machen Sie sich mit den Fluchtwegen f\u00fcr Notf\u00e4lle in Ihrem Hotelzimmer sowie den Notrufeinrichtungen vertraut. Gerade bei mehrst\u00f6ckigen H\u00e4usern ist h\u00e4ufig kein direkter Zugang ins Freie gegeben. Dies gilt auch f\u00fcr h\u00e4ufig etwas abgelegene Hotelbereiche, wie z.B. Wellness-, Indoor-Sport-Bereich und Disco. Achten Sie auf die vorhandenen Feuerl\u00f6scher und Erste-Hilfe-K\u00e4sten und merken Sie sich deren [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":2,"featured_media":9371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-9370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sicherheitshinweise","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/posts\/9370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/comments?post=9370"}],"version-history":[{"count":2,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/posts\/9370\/revisions"}],"predecessor-version":[{"id":11653,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/posts\/9370\/revisions\/11653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/media\/9371"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/media?parent=9370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/categories?post=9370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/riviera-maya\/wp-json\/wp\/v2\/tags?post=9370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}