{"id":2334,"date":"2025-01-08T18:05:46","date_gmt":"2025-01-08T17:05:46","guid":{"rendered":"https:\/\/rldev.dts.dmcit.tech\/menorca\/?p=2334"},"modified":"2025-05-01T15:05:24","modified_gmt":"2025-05-01T14:05:24","slug":"wie-kann-ich-aktivitaeten-oder-ausfluege-buchen","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/faq\/aktivitaeten-ausfluege\/wie-kann-ich-aktivitaeten-oder-ausfluege-buchen\/","title":{"rendered":"Wie kann ich Aktivit\u00e4ten oder Ausfl\u00fcge buchen?","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Aktivit\u00e4ten und Ausfl\u00fcge k\u00f6nnen Sie ganz einfach online oder direkt \u00fcber Ihre Reiseleitung im Hotel buchen.<\/p>\n<p>Auf unserer Website finden Sie eine detaillierte \u00dcbersicht aller angebotenen Aktivit\u00e4ten sowie die jeweiligen Buchungsoptionen.<\/p>\n<p>Unser Team steht Ihnen gerne zur Verf\u00fcgung, um Ihnen bei der Auswahl und Buchung der passenden Aktivit\u00e4ten zu helfen und sicherzustellen, dass Sie das Beste aus Ihrem Aufenthalt herausholen.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Aktivit\u00e4ten und Ausfl\u00fcge k\u00f6nnen Sie ganz einfach online oder direkt \u00fcber Ihre Reiseleitung im Hotel buchen. Auf unserer Website finden Sie eine detaillierte \u00dcbersicht aller angebotenen Aktivit\u00e4ten sowie die jeweiligen Buchungsoptionen. Unser Team steht Ihnen gerne zur Verf\u00fcgung, um Ihnen bei der Auswahl und Buchung der passenden Aktivit\u00e4ten zu helfen und sicherzustellen, dass Sie das [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[193],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","hentry","category-aktivitaeten-ausfluege","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":3,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":4042,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/2334\/revisions\/4042"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}