{"id":9383,"date":"2025-03-23T14:54:39","date_gmt":"2025-03-23T13:54:39","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/uncategorized\/hammamet\/"},"modified":"2025-10-03T15:58:26","modified_gmt":"2025-10-03T14:58:26","slug":"hammamet","status":"publish","type":"post","link":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/infos-a-z\/orte-infos-a-z\/hammamet\/","title":{"rendered":"Hammamet","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<h3>Urlaubsoase f\u00fcr Anspruchsvolle<\/h3>\n<p>Das einstige Seer\u00e4ubernest \u2013 eine arabische Gr\u00fcndung aus dem 16. Jh. um die schon vorher existierende Festung \u2013 mit seiner noch vollst\u00e4ndig umwallten Medina wurde schon in den 20er-Jahren von K\u00fcnstlern und Intellektuellen f\u00fcr den Fremdenverkehr entdeckt. Besonders der rum\u00e4nische Million\u00e4r Sebastian, dessen einstige Villa vom Staat aufgekauft wurde und heute als Kulturzentrum dient, machte den Ort bekannt. Auch Pers\u00f6nlichkeiten wie Flaubert, Gide, Klee und Oskar Wilde suchten hier Ruhe und Frieden. Der Boom des heutigen Massentourismus begann zu Beginn der 60er-Jahre. Das Ortsbild wurde den Bed\u00fcrfnissen der Urlauber angepasst, vor den trutzigen Mauern der Altstadt entstand ein viel gr\u00f6\u00dferer, moderner Ort mit 20.000 Einwohnern. Im neuen, gepflegten Gesch\u00e4ftszentrum gegen\u00fcber der Kasbah gibt es schicke Boutiquen, Caf\u00e9s und Restaurants.<\/p>\n<p>Der Feriengast findet in Hammamet reichlich Unterhaltungs- und Sportm\u00f6glichkeiten, die \u00fcberf\u00fcllten Promenaden zeigen am Abend ein sonst f\u00fcr islamische L\u00e4nder ungew\u00f6hnliches Leben.<\/p>\n<p>Sehenswert ist die kleine ummauerte Medina (Altstadt), die auf einer Felszunge am Meer liegt, von beiden Seiten umgeben von herrlichen Sandstr\u00e4nden. Ihr Prunkst\u00fcck ist die Kasbah (Festung in der Altstadt) aus dem 15. Jh. Beeindrucken wird Sie dort vor allem die Urspr\u00fcnglichkeit und Farbigkeit des Lebens in den engen Gassen und auf den bunten Basaren.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Urlaubsoase f\u00fcr Anspruchsvolle Das einstige Seer\u00e4ubernest \u2013 eine arabische Gr\u00fcndung aus dem 16. Jh. um die schon vorher existierende Festung \u2013 mit seiner noch vollst\u00e4ndig umwallten Medina wurde schon in den 20er-Jahren von K\u00fcnstlern und Intellektuellen f\u00fcr den Fremdenverkehr entdeckt. Besonders der rum\u00e4nische Million\u00e4r Sebastian, dessen einstige Villa vom Staat aufgekauft wurde und heute als [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":2,"featured_media":9384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[46],"tags":[],"class_list":["post-9383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orte-infos-a-z","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","has-product-nav"],"acf":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/9383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/comments?post=9383"}],"version-history":[{"count":2,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/9383\/revisions"}],"predecessor-version":[{"id":12646,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/posts\/9383\/revisions\/12646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/media\/9384"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/media?parent=9383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/categories?post=9383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/tunesien-festland\/wp-json\/wp\/v2\/tags?post=9383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}