{"id":9607,"date":"2025-03-29T21:59:54","date_gmt":"2025-03-29T20:59:54","guid":{"rendered":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/?post_type=product&#038;p=9607"},"modified":"2025-12-15T16:09:38","modified_gmt":"2025-12-15T12:09:38","slug":"ferrari-world-abu-dhabi-dds-005-1","status":"publish","type":"product","link":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/aktivitaeten\/ferrari-world-abu-dhabi-dds-005-1\/","title":{"rendered":"Ferrari World Abu Dhabi"},"content":{"rendered":"<h3>Die \u00dcberholspur zum Familienspa\u00df &#8211; der weltweit erste Themenpark der Marke Ferrari<\/h3>\n<p>Ferrari World Abu Dhabi ist ein erstklassiger Indoor-Themenpark auf Yas Island, Abu Dhabi, und der weltweit erste Ferrari-gebrandete Themenpark.<\/p>\n<p>Der Park bietet eine aufregende Mischung aus Hochgeschwindigkeitsfahrten, immersiven Erlebnissen und Attraktionen, die die Marke Ferrari und ihr italienisches Erbe feiern, was ihn zu einem Muss f\u00fcr Autoliebhaber, Familien und Abenteuerlustige macht.<\/p>\n<p>Das k\u00f6nnen Sie erwarten:<\/p>\n<ul class=\"square\">\n<li>Globale Attraktion und \u00fcber 20 hochmoderne Attraktionen f\u00fcr die die ganze Familie<\/li>\n<li>Die schnellste Achterbahn der Welt &#8211; Formula Rossa<\/li>\n<li>62 m Adrenalin G-Force Fahrt \u00fcber die H\u00f6he des Daches<\/li>\n<li>Wechseln Sie das Tempo mit einer entspannten Tour durch das Miniatur-Italien an Bord von Bell&#8217;Italia oder einer Ferrari-Werksbesichtigung bei Made in Maranello<\/li>\n<li>Italienische Restaurants und Caf\u00e9s mit k\u00f6stlichen Speisen<\/li>\n<li>Einkaufsm\u00f6glichkeiten zum Thema Ferrari<\/li>\n<\/ul>\n<p><strong>Ausflugsveranstalter:<\/strong>\u00a0Destination Touristic Services<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00dcberholspur zum Familienspa\u00df &#8211; der weltweit erste Themenpark der Marke Ferrari Ferrari World Abu Dhabi ist ein erstklassiger Indoor-Themenpark auf Yas Island, Abu Dhabi, und der weltweit erste Ferrari-gebrandete Themenpark. Der Park bietet eine aufregende Mischung aus Hochgeschwindigkeitsfahrten, immersiven Erlebnissen und Attraktionen, die die Marke Ferrari und ihr italienisches Erbe feiern, was ihn zu [&hellip;]<\/p>\n","protected":false},"featured_media":9867,"template":"","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":9868,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":""},"ort":[532,535,537,536,538,540,541,533,539,542,534,543],"sichtbarkeit":[],"templateoption":[176],"product_brand":[],"product_cat":[182],"product_tag":[],"class_list":{"0":"post-9607","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"ort-abu-dhabi","7":"ort-abu-dhabi-desert-qasr-al-sarab","8":"ort-ajman","9":"ort-al-ain","10":"ort-dubai","11":"ort-dubai-desert","12":"ort-fujairah","13":"ort-ghantoot","14":"ort-jebel-ali","15":"ort-ras-al-khaimah","16":"ort-sir-bani-yas-island","17":"ort-umm-al-quwain","18":"templateoption-ohne-buchungskalender","19":"product_cat-ausfluege","21":"entry","22":"has-media","24":"first","25":"instock","26":"virtual","27":"purchasable","28":"product-type-simple","29":"has-product-nav","30":"col","31":"span_1_of_3","32":"owp-content-center","33":"owp-thumbs-layout-horizontal","34":"owp-btn-normal","35":"owp-tabs-layout-section"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product\/9607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":13,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product\/9607\/revisions"}],"predecessor-version":[{"id":10638,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product\/9607\/revisions\/10638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/media\/9867"}],"wp:attachment":[{"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/media?parent=9607"}],"wp:term":[{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/ort?post=9607"},{"taxonomy":"sichtbarkeit","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/sichtbarkeit?post=9607"},{"taxonomy":"templateoption","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/templateoption?post=9607"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product_brand?post=9607"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product_cat?post=9607"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.dertour-reiseleitung.com\/vereinigte-arabische-emirate\/wp-json\/wp\/v2\/product_tag?post=9607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}